{"id":326,"count":4,"description":"","link":"https:\/\/cyclingdestination.cc\/de\/category\/verhalen\/frankrijk\/auvergne","name":"Auvergne","slug":"auvergne","taxonomy":"category","parent":11,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Auvergne Archieven - Cycling Destination<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingdestination.cc\/de\/category\/verhalen\/frankrijk\/auvergne\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Auvergne Archieven - Cycling Destination\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingdestination.cc\/de\/category\/verhalen\/frankrijk\/auvergne\/\" \/>\n<meta property=\"og:site_name\" content=\"Cycling Destination\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/10\/ruben_12102022_cycling_destination_etxeondo_32-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@cyclingdestin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/category\\\/verhalen\\\/frankrijk\\\/auvergne\",\"url\":\"https:\\\/\\\/cyclingdestination.cc\\\/category\\\/verhalen\\\/frankrijk\\\/auvergne\",\"name\":\"Auvergne Archieven - Cycling Destination\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/category\\\/verhalen\\\/frankrijk\\\/auvergne#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/category\\\/verhalen\\\/frankrijk\\\/auvergne#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingdestination.cc\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Verhalen\",\"item\":\"https:\\\/\\\/cyclingdestination.cc\\\/category\\\/verhalen\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Frankrijk\",\"item\":\"https:\\\/\\\/cyclingdestination.cc\\\/category\\\/verhalen\\\/frankrijk\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Auvergne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#website\",\"url\":\"https:\\\/\\\/cyclingdestination.cc\\\/\",\"name\":\"Cycling Destination\",\"description\":\"Inspiratie voor jouw volgende fietsavontuur\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingdestination.cc\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#organization\",\"name\":\"Cycling Destination\",\"url\":\"https:\\\/\\\/cyclingdestination.cc\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingdestination.cc\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/cyclingdestination_logo_RGB_zwart_vDEF-1.png\",\"contentUrl\":\"https:\\\/\\\/cyclingdestination.cc\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/cyclingdestination_logo_RGB_zwart_vDEF-1.png\",\"width\":2550,\"height\":814,\"caption\":\"Cycling Destination\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cyclingdestination.cc\",\"https:\\\/\\\/x.com\\\/cyclingdestin\",\"https:\\\/\\\/www.instagram.com\\\/cyclingdestination.cc\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Auvergne Archieven - Cycling Destination","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingdestination.cc\/de\/category\/verhalen\/frankrijk\/auvergne\/","og_locale":"de_DE","og_type":"article","og_title":"Auvergne Archieven - Cycling Destination","og_url":"https:\/\/cyclingdestination.cc\/de\/category\/verhalen\/frankrijk\/auvergne\/","og_site_name":"Cycling Destination","og_image":[{"width":2048,"height":2560,"url":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/10\/ruben_12102022_cycling_destination_etxeondo_32-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@cyclingdestin","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/cyclingdestination.cc\/category\/verhalen\/frankrijk\/auvergne","url":"https:\/\/cyclingdestination.cc\/category\/verhalen\/frankrijk\/auvergne","name":"Auvergne Archive - Reiseziel Radsport","isPartOf":{"@id":"https:\/\/cyclingdestination.cc\/#website"},"breadcrumb":{"@id":"https:\/\/cyclingdestination.cc\/category\/verhalen\/frankrijk\/auvergne#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingdestination.cc\/category\/verhalen\/frankrijk\/auvergne#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingdestination.cc\/"},{"@type":"ListItem","position":2,"name":"Verhalen","item":"https:\/\/cyclingdestination.cc\/category\/verhalen"},{"@type":"ListItem","position":3,"name":"Frankrijk","item":"https:\/\/cyclingdestination.cc\/category\/verhalen\/frankrijk"},{"@type":"ListItem","position":4,"name":"Auvergne"}]},{"@type":"WebSite","@id":"https:\/\/cyclingdestination.cc\/#website","url":"https:\/\/cyclingdestination.cc\/","name":"Ziel Radfahren","description":"Inspiration f\u00fcr Ihr n\u00e4chstes Fahrradabenteuer","publisher":{"@id":"https:\/\/cyclingdestination.cc\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingdestination.cc\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/cyclingdestination.cc\/#organization","name":"Ziel Radfahren","url":"https:\/\/cyclingdestination.cc\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cyclingdestination.cc\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/01\/cyclingdestination_logo_RGB_zwart_vDEF-1.png","contentUrl":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/01\/cyclingdestination_logo_RGB_zwart_vDEF-1.png","width":2550,"height":814,"caption":"Cycling Destination"},"image":{"@id":"https:\/\/cyclingdestination.cc\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cyclingdestination.cc","https:\/\/x.com\/cyclingdestin","https:\/\/www.instagram.com\/cyclingdestination.cc\/"]}]}},"_links":{"self":[{"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/categories\/326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/categories\/11"}],"wp:post_type":[{"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/posts?categories=326"},{"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/pages?categories=326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}