{"id":1587,"date":"2021-10-14T19:21:41","date_gmt":"2021-10-14T19:21:41","guid":{"rendered":"https:\/\/cyclingdestination.cc\/?p=1587"},"modified":"2024-07-12T11:31:52","modified_gmt":"2024-07-12T09:31:52","slug":"fietsen-in-de-isere-alpe-dhuez-en-meer","status":"publish","type":"post","link":"https:\/\/cyclingdestination.cc\/de\/verhalen\/fietsen-in-de-isere-alpe-dhuez-en-meer","title":{"rendered":"Radfahren im Departement Is\u00e8re: Alpe d'Huez und mehr"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Wenn Fahrrad in Frankreich sagt <a href=\"https:\/\/cutt.ly\/LLg0HTf\" target=\"_blank\" rel=\"noreferrer noopener\">Is\u00e8re<\/a>. Das wiederum ist gleichbedeutend mit Bourg d'Oisans, und sobald Sie in Bourg d'Oisans sind, k\u00f6nnen Sie nur noch an die Alpe denken: Alpe d'Huez. Mit ihren 21 Kurven, ihrer reichen Geschichte f\u00fcr Profis, Anf\u00e4nger und alles, was dazwischen liegt, befinden Sie sich hier im pulsierenden Herzen des Radtourismus.  Doch Kenner sind sich einig: \"Die Alpe\" ist weder der sch\u00f6nste noch der schwierigste Anstieg, den es gibt. In der Tat gibt es vielleicht 100 Berge, die interessanter sind als die Alpe D'Huez. Es gibt sogar einen <a href=\"https:\/\/www.cycling-challenge.com\/100-cycling-climbs-better-than-alpe-dhuez\/\" target=\"_blank\" rel=\"noreferrer noopener\">gesamte Website<\/a> ihr gewidmet. Wir ruhen uns aus. Deshalb stellen wir jetzt einige Alternativen zum Radfahren auf der Is\u00e8re vor, die vielleicht mehr Spa\u00df machen, schwieriger oder sch\u00f6ner sind als die \"21 virages d'Alpe D'Huez\".<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"290\" data-id=\"2363\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/Panorama-21turns-1024x290.jpg\" alt=\"\" class=\"wp-image-2363\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/Panorama-21turns-1024x290.jpg 1024w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/Panorama-21turns-300x85.jpg 300w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/Panorama-21turns-768x218.jpg 768w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/Panorama-21turns.jpg 1284w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Oberstdorf von Vaujany<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Dieser kleine Riese wird irgendwie kaum erw\u00e4hnt, wenn es um die Isere geht. Sie finden ihn in den beiden Vaujany-Veranstaltungen von <a data-type=\"URL\" data-id=\"www.gfny.com\" href=\"http:\/\/www.gfny.com\" target=\"_blank\" rel=\"noreferrer noopener\">GFNY<\/a> aber ansonsten scheinen die Leute diesen Anstieg zu ignorieren. Vielleicht liegt es daran, dass dieser Anstieg (auch) eine Sackgasse ist und sich daher nicht unbedingt f\u00fcr eine gute Runde eignet. Aber mit 9,4 Kilometern und einer Steilheit, die sich mit der des Passo Giau misst, wird man hier auf seine Kosten kommen.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"413\" data-id=\"2369\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/vaujany-1024x413.jpg\" alt=\"\" class=\"wp-image-2369\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/vaujany-1024x413.jpg 1024w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/vaujany-300x121.jpg 300w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/vaujany-768x310.jpg 768w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/vaujany.jpg 1140w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Alpe d'Huez die andere Seite:<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn man von Alpe d'Huez spricht, gibt es nur eine Seite. Diejenige mit den 21 Kurven. Es geht immer um die holl\u00e4ndische Kurve, Kurve 7. Um die Weltbestzeit des verstorbenen Marco Pantani. Aber es gibt auch eine andere Seite. Die ist weniger spektakul\u00e4r und weniger mit Radsportgeschichte \u00fcberh\u00e4uft. Aber wenn man schon mal in der Gegend ist. Die Strecke ist von der Steigung her viel angenehmer und man f\u00e4hrt den letzten Teil auf der gleichen Strecke wie den ber\u00fchmteren Anstieg. Dieser Pass ist auch unter dem Namen Pas de la Confession bekannt. Sie starten im Dorf Allemond, also nicht in Bourg d'Oisans.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auf dem Gipfel angekommen, haben Sie drei M\u00f6glichkeiten: <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Direkt zur\u00fcck \u00fcber den gleichen Weg<\/li>\n\n\n\n<li>Zur\u00fcck \u00fcber die ber\u00fchmten 21 Kurven<\/li>\n\n\n\n<li>Weiter zum Col de Sarenne<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Wir w\u00fcrden uns f\u00fcr Letzteres entscheiden, dann zum Stausee hinuntersteigen und dann eine sch\u00f6ne Tour durch die Gegend machen. Nicht schlecht, wenn es nach uns ginge. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Col du Sabot<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00f6rdlich von Alpe d'Huez finden Sie diesen sch\u00f6nen Anstieg. Es handelt sich um eine \"Einbahnstra\u00dfe\", d.h. Sie m\u00fcssen leider denselben Weg hinauffahren, wenn Sie auch wieder hinunterfahren m\u00fcssen. Aber um es klar zu sagen: dieser Aufstieg ist sehr empfehlenswert. Der Gipfel ist deutlich h\u00f6her als sein Nachbar, denn auf insgesamt 14,5 Kilometern und mit einem Prozentsatz von 8,9 bringt Sie diese Stra\u00dfe auf 2.100 Meter H\u00f6he. Daf\u00fcr ist es viel ruhiger und die Aussicht ist viel besser als bei seinem ber\u00fchmten Bruder. Dabei ist die Anzahl der Haarnadelkurven sicher nicht schlecht. <\/p>\n\n\n\n<blockquote class=\"mycols-embed-col\"><p lang=\"en\"><a href=\"https:\/\/mycols.app\/col\/col-du-sabot\" target=\"_blank\" rel=\"noopener\">Col du Sabot<\/a>Vaujany, Frankreich<\/p>- Entfernung: 14,6 km, H\u00f6he: 1248 m, durchschnittl. Steigung: 8,5 %<\/blockquote> <script async src=\"https:\/\/mycols.app\/js\/embed.js\" charset=\"utf-8\"><\/script>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"750\" height=\"422\" data-id=\"2366\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/89436007_1318012351726113_1232681495424925696_n.jpg\" alt=\"\" class=\"wp-image-2366\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/89436007_1318012351726113_1232681495424925696_n.jpg 750w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/89436007_1318012351726113_1232681495424925696_n-300x169.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><figcaption class=\"wp-element-caption\">(c) MyCols<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Col du Parquetout<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wir haben diesen Aufstieg schon einmal gesehen, und zwar in unserer \u00dcbersicht der P\u00e4sse, auf denen man <a href=\"https:\/\/cyclingdestination.cc\/de\/stories\/vijf-beklimmingen-in-de-franse-en-zwitserse-alpen-die-jij-waarschijnlijk-niet-kent\/\" data-type=\"post\" data-id=\"1250\">wahrscheinlich noch nie geh\u00f6rt. <\/a> Ein genialer Klettersteig, der nicht unbedingt hoch wird, also auch l\u00e4nger im Jahr Chancen bietet. Dieser hier wird allerdings weh tun! Mit nur 1382 Metern ist er also kein \u00dcberflieger, aber auf 7,1 Kilometern klettert man mit durchschnittlich 9,7% nach oben. Zumindest, wenn man die steile Seite nimmt. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"413\" data-id=\"2370\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/balade-faite-par-le-col-2.jpg\" alt=\"\" class=\"wp-image-2370\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/balade-faite-par-le-col-2.jpg 550w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/balade-faite-par-le-col-2-300x225.jpg 300w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Mehr Infos<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Region hat noch viel mehr zu bieten als die oben genannten Tipps. Besuchen Sie die <a href=\"https:\/\/nl.bike-oisans.com\">Standort von Oisans<\/a>Dort finden Sie eine Menge toller Routen und Alternativen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch der Standort von <a rel=\"noreferrer noopener\" href=\"https:\/\/www.isere-tourisme.com\/selection\/offices-de-tourisme\" data-type=\"URL\" data-id=\"https:\/\/www.isere-tourisme.com\/selection\/offices-de-tourisme\" target=\"_blank\">Isere Tourisme<\/a> bietet eine F\u00fclle von Informationen \u00fcber die Region. Viel Spa\u00df beim Radfahren!<\/p>","protected":false},"excerpt":{"rendered":"<p>Als fiets in Frankrijk zegt, dan zeg je Is\u00e8re. Dat staat weer gelijk aan Bourg d&#8217;Oisans en eenmaal in Bourg d&#8217;Oisans kun je alleen maar denken aan De Alpe: Alpe d&#8217;Huez. Met zijn 21 bochten, rijke historie voor zowel profs, beginners en alles daartussen in ben je hier in het kloppende hart van het fietstoerisme. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2362,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"iawp_total_views":427,"footnotes":""},"categories":[11,242,8],"tags":[],"class_list":["post-1587","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-frankrijk","category-franse-alpen","category-verhalen"],"acf":[],"featured_image_url":{"thumbnail":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/Een-gedeelte-van-het-parcours-Rechten-archief-RTV-Drenthe-150x150.jpg","medium":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/Een-gedeelte-van-het-parcours-Rechten-archief-RTV-Drenthe-300x169.jpg","medium_large":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/Een-gedeelte-van-het-parcours-Rechten-archief-RTV-Drenthe-768x432.jpg","large":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/Een-gedeelte-van-het-parcours-Rechten-archief-RTV-Drenthe.jpg","1536x1536":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/Een-gedeelte-van-het-parcours-Rechten-archief-RTV-Drenthe.jpg","2048x2048":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/Een-gedeelte-van-het-parcours-Rechten-archief-RTV-Drenthe.jpg","trp-custom-language-flag":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/Een-gedeelte-van-het-parcours-Rechten-archief-RTV-Drenthe.jpg"},"post_author":"Sander","assigned_categories":"Frankrijk, Franse Alpen, Verhalen","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fietsen in de Is\u00e8re: Alpe d&#039;Huez en meer - Cycling Destination<\/title>\n<meta name=\"description\" content=\"Fietsen in de Is\u00e8re. Je denkt gelijk aan Alpe d&#039;Huez, maar er is zoveel meer om te ontdekken in deze prachtige regio. Check onze tips!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingdestination.cc\/de\/verhalen\/fietsen-in-de-isere-alpe-dhuez-en-meer\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fietsen in de Is\u00e8re: Alpe d&#039;Huez en meer - Cycling Destination\" \/>\n<meta property=\"og:description\" content=\"Fietsen in de Is\u00e8re. Je denkt gelijk aan Alpe d&#039;Huez, maar er is zoveel meer om te ontdekken in deze prachtige regio. Check onze tips!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingdestination.cc\/de\/verhalen\/fietsen-in-de-isere-alpe-dhuez-en-meer\/\" \/>\n<meta property=\"og:site_name\" content=\"Cycling Destination\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cyclingdestination.cc\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-14T19:21:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-12T09:31:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/Een-gedeelte-van-het-parcours-Rechten-archief-RTV-Drenthe.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"770\" \/>\n\t<meta property=\"og:image:height\" content=\"433\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sander\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cyclingdestin\" \/>\n<meta name=\"twitter:site\" content=\"@cyclingdestin\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sander\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-de-isere-alpe-dhuez-en-meer#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-de-isere-alpe-dhuez-en-meer\"},\"author\":{\"name\":\"Sander\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#\\\/schema\\\/person\\\/d1466484f28fb18fca7147996a53f7b8\"},\"headline\":\"Fietsen in de Is\u00e8re: Alpe d&#8217;Huez en meer\",\"datePublished\":\"2021-10-14T19:21:41+00:00\",\"dateModified\":\"2024-07-12T09:31:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-de-isere-alpe-dhuez-en-meer\"},\"wordCount\":629,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-de-isere-alpe-dhuez-en-meer#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingdestination.cc\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Een-gedeelte-van-het-parcours-Rechten-archief-RTV-Drenthe.jpg\",\"articleSection\":[\"Frankrijk\",\"Franse Alpen\",\"Verhalen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-de-isere-alpe-dhuez-en-meer#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-de-isere-alpe-dhuez-en-meer\",\"url\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-de-isere-alpe-dhuez-en-meer\",\"name\":\"Fietsen in de Is\u00e8re: Alpe d'Huez en meer - Cycling Destination\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-de-isere-alpe-dhuez-en-meer#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-de-isere-alpe-dhuez-en-meer#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingdestination.cc\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Een-gedeelte-van-het-parcours-Rechten-archief-RTV-Drenthe.jpg\",\"datePublished\":\"2021-10-14T19:21:41+00:00\",\"dateModified\":\"2024-07-12T09:31:52+00:00\",\"description\":\"Fietsen in de Is\u00e8re. Je denkt gelijk aan Alpe d'Huez, maar er is zoveel meer om te ontdekken in deze prachtige regio. Check onze tips!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-de-isere-alpe-dhuez-en-meer#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-de-isere-alpe-dhuez-en-meer\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-de-isere-alpe-dhuez-en-meer#primaryimage\",\"url\":\"https:\\\/\\\/cyclingdestination.cc\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Een-gedeelte-van-het-parcours-Rechten-archief-RTV-Drenthe.jpg\",\"contentUrl\":\"https:\\\/\\\/cyclingdestination.cc\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Een-gedeelte-van-het-parcours-Rechten-archief-RTV-Drenthe.jpg\",\"width\":770,\"height\":433},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-de-isere-alpe-dhuez-en-meer#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingdestination.cc\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fietsen in de Is\u00e8re: Alpe d&#8217;Huez en meer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#website\",\"url\":\"https:\\\/\\\/cyclingdestination.cc\\\/\",\"name\":\"Cycling Destination\",\"description\":\"Inspiratie voor jouw volgende fietsavontuur\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingdestination.cc\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#organization\",\"name\":\"Cycling Destination\",\"url\":\"https:\\\/\\\/cyclingdestination.cc\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingdestination.cc\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/cyclingdestination_logo_RGB_zwart_vDEF-1.png\",\"contentUrl\":\"https:\\\/\\\/cyclingdestination.cc\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/cyclingdestination_logo_RGB_zwart_vDEF-1.png\",\"width\":2550,\"height\":814,\"caption\":\"Cycling Destination\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cyclingdestination.cc\",\"https:\\\/\\\/x.com\\\/cyclingdestin\",\"https:\\\/\\\/www.instagram.com\\\/cyclingdestination.cc\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#\\\/schema\\\/person\\\/d1466484f28fb18fca7147996a53f7b8\",\"name\":\"Sander\",\"url\":\"https:\\\/\\\/cyclingdestination.cc\\\/de\\\/author\\\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Radfahren im Departement Is\u00e8re: Alpe d'Huez und mehr - Cycling Destination","description":"Radfahren im Departement Is\u00e8re. Man denkt sofort an Alpe d'Huez, aber es gibt so viel mehr in dieser sch\u00f6nen Region zu entdecken. Sehen Sie sich unsere Tipps an!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingdestination.cc\/de\/verhalen\/fietsen-in-de-isere-alpe-dhuez-en-meer\/","og_locale":"de_DE","og_type":"article","og_title":"Fietsen in de Is\u00e8re: Alpe d'Huez en meer - Cycling Destination","og_description":"Fietsen in de Is\u00e8re. Je denkt gelijk aan Alpe d'Huez, maar er is zoveel meer om te ontdekken in deze prachtige regio. Check onze tips!","og_url":"https:\/\/cyclingdestination.cc\/de\/verhalen\/fietsen-in-de-isere-alpe-dhuez-en-meer\/","og_site_name":"Cycling Destination","article_publisher":"https:\/\/www.facebook.com\/cyclingdestination.cc","article_published_time":"2021-10-14T19:21:41+00:00","article_modified_time":"2024-07-12T09:31:52+00:00","og_image":[{"width":770,"height":433,"url":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/Een-gedeelte-van-het-parcours-Rechten-archief-RTV-Drenthe.jpg","type":"image\/jpeg"}],"author":"Sander","twitter_card":"summary_large_image","twitter_creator":"@cyclingdestin","twitter_site":"@cyclingdestin","twitter_misc":{"Verfasst von":"Sander","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-de-isere-alpe-dhuez-en-meer#article","isPartOf":{"@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-de-isere-alpe-dhuez-en-meer"},"author":{"name":"Sander","@id":"https:\/\/cyclingdestination.cc\/#\/schema\/person\/d1466484f28fb18fca7147996a53f7b8"},"headline":"Fietsen in de Is\u00e8re: Alpe d&#8217;Huez en meer","datePublished":"2021-10-14T19:21:41+00:00","dateModified":"2024-07-12T09:31:52+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-de-isere-alpe-dhuez-en-meer"},"wordCount":629,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingdestination.cc\/#organization"},"image":{"@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-de-isere-alpe-dhuez-en-meer#primaryimage"},"thumbnailUrl":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/Een-gedeelte-van-het-parcours-Rechten-archief-RTV-Drenthe.jpg","articleSection":["Frankrijk","Franse Alpen","Verhalen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-de-isere-alpe-dhuez-en-meer#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-de-isere-alpe-dhuez-en-meer","url":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-de-isere-alpe-dhuez-en-meer","name":"Radfahren im Departement Is\u00e8re: Alpe d'Huez und mehr - Cycling Destination","isPartOf":{"@id":"https:\/\/cyclingdestination.cc\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-de-isere-alpe-dhuez-en-meer#primaryimage"},"image":{"@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-de-isere-alpe-dhuez-en-meer#primaryimage"},"thumbnailUrl":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/Een-gedeelte-van-het-parcours-Rechten-archief-RTV-Drenthe.jpg","datePublished":"2021-10-14T19:21:41+00:00","dateModified":"2024-07-12T09:31:52+00:00","description":"Radfahren im Departement Is\u00e8re. Man denkt sofort an Alpe d'Huez, aber es gibt so viel mehr in dieser sch\u00f6nen Region zu entdecken. Sehen Sie sich unsere Tipps an!","breadcrumb":{"@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-de-isere-alpe-dhuez-en-meer#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-de-isere-alpe-dhuez-en-meer"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-de-isere-alpe-dhuez-en-meer#primaryimage","url":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/Een-gedeelte-van-het-parcours-Rechten-archief-RTV-Drenthe.jpg","contentUrl":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/Een-gedeelte-van-het-parcours-Rechten-archief-RTV-Drenthe.jpg","width":770,"height":433},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-de-isere-alpe-dhuez-en-meer#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingdestination.cc\/"},{"@type":"ListItem","position":2,"name":"Fietsen in de Is\u00e8re: Alpe d&#8217;Huez en meer"}]},{"@type":"WebSite","@id":"https:\/\/cyclingdestination.cc\/#website","url":"https:\/\/cyclingdestination.cc\/","name":"Ziel Radfahren","description":"Inspiration f\u00fcr Ihr n\u00e4chstes Fahrradabenteuer","publisher":{"@id":"https:\/\/cyclingdestination.cc\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingdestination.cc\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/cyclingdestination.cc\/#organization","name":"Ziel Radfahren","url":"https:\/\/cyclingdestination.cc\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cyclingdestination.cc\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/01\/cyclingdestination_logo_RGB_zwart_vDEF-1.png","contentUrl":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/01\/cyclingdestination_logo_RGB_zwart_vDEF-1.png","width":2550,"height":814,"caption":"Cycling Destination"},"image":{"@id":"https:\/\/cyclingdestination.cc\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cyclingdestination.cc","https:\/\/x.com\/cyclingdestin","https:\/\/www.instagram.com\/cyclingdestination.cc\/"]},{"@type":"Person","@id":"https:\/\/cyclingdestination.cc\/#\/schema\/person\/d1466484f28fb18fca7147996a53f7b8","name":"Sander","url":"https:\/\/cyclingdestination.cc\/de\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/posts\/1587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/comments?post=1587"}],"version-history":[{"count":0,"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/posts\/1587\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/media\/2362"}],"wp:attachment":[{"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/media?parent=1587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/categories?post=1587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/tags?post=1587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}