{"id":2097,"date":"2021-10-02T16:00:36","date_gmt":"2021-10-02T16:00:36","guid":{"rendered":"https:\/\/cyclingdestination.cc\/?p=2097"},"modified":"2025-04-23T12:55:24","modified_gmt":"2025-04-23T10:55:24","slug":"fietsen-in-kroatie","status":"publish","type":"post","link":"https:\/\/cyclingdestination.cc\/de\/verhalen\/fietsen-in-kroatie","title":{"rendered":"Radfahren in Istrien ist Ihr erster Halt in Kroatien"},"content":{"rendered":"<p>Radfahren in Europa ist fantastisch. Radfahren in Kroatien und insbesondere in Istrien ist da keine Ausnahme. Denn hier gibt es nicht nur hohe Berge, atemberaubende Abfahrten, Kopfsteinpflaster, Schotterwege, Seewege und vieles mehr. Sie k\u00f6nnen zu jeder Jahreszeit andere Regionen und Landschaften genie\u00dfen. In der Tat beispiellos. Einige Reiseziele sind bereits komplett ausgebucht. Aber ist es m\u00f6glich, ganz Frankreich in seinem Leben zu bereisen? Oder ganz Spanien? Ziemlich schwierig, aber immerhin. Die <a data-type=\"post\" data-id=\"1817\" href=\"https:\/\/cyclingdestination.cc\/de\/bestemmingen\/5-mytische-cols-in-de-pyreneeen\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pyren\u00e4en<\/a> Ob die <a data-type=\"post\" data-id=\"1250\" href=\"https:\/\/cyclingdestination.cc\/de\/bestemmingen\/vijf-beklimmingen-in-de-franse-en-zwitserse-alpen-die-jij-waarschijnlijk-niet-kent\/\" target=\"_blank\" rel=\"noreferrer noopener\">Alpen<\/a> ist bereits eine gro\u00dfe Herausforderung. <\/p>\n\n\n\n<p>In den letzten Jahren sind die L\u00e4nder rund um das Adriatische Meer auf dem Vormarsch. <a data-type=\"post\" data-id=\"1483\" href=\"https:\/\/cyclingdestination.cc\/de\/bestemmingen\/slovenie-land-van-tourwinnaars-beklimmingen-en-schitterende-uitzichten\/\" target=\"_blank\" rel=\"noreferrer noopener\">Slowenien<\/a> ist ein deutliches Beispiel, aber auch das benachbarte Kroatien profiliert sich zunehmend als Radreiseziel. Das Radfahren in Kroatien gewinnt immer mehr an Aufmerksamkeit. Istrien ist eine wundersch\u00f6ne Region und liegt in der N\u00e4he von Italien und Slowenien, was gute M\u00f6glichkeiten f\u00fcr eine Drei-L\u00e4nder-Tour bietet. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large is-style-default\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"2098\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/00-HOMEPAGE-Slider-Slide-01-e1568136599378-1024x683.jpg\" alt=\"\" class=\"wp-image-2098\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/00-HOMEPAGE-Slider-Slide-01-e1568136599378-1024x683.jpg 1024w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/00-HOMEPAGE-Slider-Slide-01-e1568136599378-300x200.jpg 300w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/00-HOMEPAGE-Slider-Slide-01-e1568136599378-768x512.jpg 768w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/00-HOMEPAGE-Slider-Slide-01-e1568136599378-1536x1024.jpg 1536w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/00-HOMEPAGE-Slider-Slide-01-e1568136599378.jpg 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">(c) Istrien300.hr<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Zahlreiche Optionen<\/h2>\n\n\n\n<p>Wer einen Blick auf die Landkarte wirft, wird es sofort erkennen. Hrvatska, Kroatien, ist langgestreckt und ein wenig wie ein T geformt. Das bedeutet, dass Sie unz\u00e4hlige M\u00f6glichkeiten haben, an der K\u00fcste entlang zu fahren, aber auch im Landesinneren gibt es viel Abwechslung beim Radfahren. Kroatien ist in mehrere Regionen unterteilt, und die bekannteste ist sicherlich Istrien. Das Gebiet ist gro\u00df genug, um mehrere Tage hintereinander verschiedene Routen zu fahren. Mit dem Vojak im Ucka-Nationalpark haben Sie auch den besten Anstieg Kroatiens. Also los geht's!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Radfahren in Istrien: Nationalpark Ucka<\/h2>\n\n\n\n<p>Um es gleich auf den Punkt zu bringen: der Vojak oder Ucka-Pass, wie er auch genannt wird. Mit seinen 1372 Metern ist er ein steiler Pickel, der sich im Winter manchmal wei\u00df f\u00e4rbt. Man kann diesen Pass, der eigentlich der einzige wirklich hohe Anstieg in Istrien ist, von drei Seiten angehen. Die schwierigste Variante ist die westliche, von Vranja aus. Dies ist auch diejenige, die wirklich in Istrien liegt. Wenn man 13,5 Kilometer mit durchschnittlich 8,1% klettern muss, hat man hier eine ernsthafte Herausforderung, die mit den h\u00e4rtesten alpinen Anstiegen konkurrieren kann. Eine maximale Steigung von 14,5% ist keine Kleinigkeit. Auf dem Gipfel befindet sich ein Aussichtsturm, von dem aus man den gesamten Park \u00fcberblicken kann. Wahrlich gro\u00dfartig. Die Besteigung dieses Passes l\u00e4sst sich gut mit einer Route vom Plomin aus kombinieren, von wo aus man ebenfalls einen herrlichen Blick auf die Bucht hat. Sie k\u00f6nnen dann ins Landesinnere und zur\u00fcck entlang der K\u00fcste (der Provinz Primorje - Gorski Kotar) fahren.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"501\" data-id=\"2101\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/03_Vojak-iz-zraka-01-Alan-Caplar-dronom-1-1024x501.jpg\" alt=\"\" class=\"wp-image-2101\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/03_Vojak-iz-zraka-01-Alan-Caplar-dronom-1-1024x501.jpg 1024w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/03_Vojak-iz-zraka-01-Alan-Caplar-dronom-1-300x147.jpg 300w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/03_Vojak-iz-zraka-01-Alan-Caplar-dronom-1-768x376.jpg 768w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/03_Vojak-iz-zraka-01-Alan-Caplar-dronom-1.jpg 1140w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Ucka-Nationalpark - Vojak (C)Alan Caplar - visitcroatia<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Der einzige Weg f\u00fchrt nach oben<\/h3>\n\n\n\n<p>Im Park gibt es eigentlich nur 1 asphaltierte Stra\u00dfe hinauf zum Gipfel. F\u00fcr die Schotterliebhaber gibt es einige weitere Alternativen. Auch hier kann man von Plomin aus ins Landesinnere fahren, bei Kozljak in den Park eintreten und unbefestigt aufsteigen. Das ist eine sch\u00f6ne Alternative, bei der man allerdings mit heftigen Steigungen rechnen muss. Am Ende kann man hin und her fahren, eine kleine Schleife machen und auf 66 Kilometern fast 2.500 H\u00f6henmeter bew\u00e4ltigen. Und das mit Abschnitten von 20 bis 25%. Das ist aber wirklich sch\u00f6n. Man radelt zwischen H\u00fcgeln und Bergen und wenn man genau hinschaut, sieht man links und rechts eine alte Ruine oder einen sch\u00f6nen Aussichtspunkt. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ein alternativer Punkt im Dreil\u00e4ndereck<\/h2>\n\n\n\n<p>Die Nordseite der Halbinsel ist fast flach, abgesehen von einigen steilen H\u00fcgeln. Einer der sch\u00f6nsten Orte ist der jahrhundertealte Leuchtturm von Savudrija, von dem aus man einen tollen Blick auf den schmalen Streifen zwischen Slowenien und Italien hat: ein alternatives Dreil\u00e4ndereck also. Wenn Sie mit dem Schotterrad unterwegs sind, k\u00f6nnen Sie hier eine fantastische Route dicht an der K\u00fcste entlang in Richtung S\u00fcden zu den St\u00e4dten Monterol und Umag fahren. Auch in Richtung Osten zur slowenischen Grenze gibt es eine solche Strecke. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"960\" height=\"540\" data-id=\"2107\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/g0ecdsfaruf11.jpeg\" alt=\"\" class=\"wp-image-2107\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/g0ecdsfaruf11.jpeg 960w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/g0ecdsfaruf11-300x169.jpeg 300w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/g0ecdsfaruf11-768x432.jpeg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>Mit dem Rennrad werden Sie bald mehr ins Landesinnere \"gezwungen\", aber dort haben Sie viel Unterhaltung. Fahren Sie in die Stadt Buje und Sie werden mit einem kleinen H\u00fcgel \u00fcberrascht, der in einem fl\u00e4mischen Klassiker nicht fehl am Platz w\u00e4re. Nur 500 Meter weiter mit einem guten St\u00fcck \u00fcber 11%. Ein wenig weiter liegt auch die Stadt Triban, die vielen vor allem durch die <a href=\"https:\/\/www.decathlon.nl\/browse\/b\/triban\/_\/N-1alpz06\" target=\"_blank\" rel=\"noreferrer noopener\">Decathlon<\/a> Fahrradausr\u00fcstung. Radfahren in Istrien ist fantastisch.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Weine, Weine, Weine!<\/h2>\n\n\n\n<p>Weiter im Landesinneren finden Sie auch die Weinregionen, wo Sie sch\u00f6n zwischen den Weinbergen fahren k\u00f6nnen. Auch das ist ein tolles Fotomotiv. Es ist auch cool, den Livade-Anstieg zu fahren. Es kommt ein bisschen darauf an, wie man misst, aber man k\u00f6nnte sie insgesamt fast 6 Kilometer lang machen, einschlie\u00dflich der Haarnadelkurven! Trotzdem, das ist ziemlich cool. Mit einem sehr steilen Abschnitt, der \u00fcber dem Durchschnitt von 10% liegt, sollte man sich diese Strecke in seinem Urlaub nicht entgehen lassen. Man k\u00f6nnte fast meinen, man sei in <a rel=\"noreferrer noopener\" href=\"https:\/\/cyclingdestination.cc\/de\/bestemmingen\/toscane-rolling-hills-for-ages\/\" data-type=\"post\" data-id=\"1795\" target=\"_blank\">Toskana<\/a> sind. Sicherlich hat man von Motovun aus eine tolle Aussicht. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"2112\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/Istria-Motovun-VI.jpeg\" alt=\"\" class=\"wp-image-2112\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/Istria-Motovun-VI.jpeg 1024w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/Istria-Motovun-VI-300x225.jpeg 300w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/Istria-Motovun-VI-768x576.jpeg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Pula und Umgebung<\/h2>\n\n\n\n<p>Es ist nat\u00fcrlich m\u00f6glich, von Norden her entlang der K\u00fcste bis nach Pula zu fahren. Diese Stra\u00dfe ist herrlich h\u00fcgelig. Pula ist auf jeden Fall einen Besuch wert, schon allein wegen des Amphitheaters. Ebenfalls vor der K\u00fcste von Pula befindet sich der Nationalpark Brijuni. Der ist auch wundersch\u00f6n, aber mit einem Fahrrad mit breiten Reifen. S\u00fcdlich von Pula gibt es auch eine Art Halbinsel, auf der man gut fahren kann. Au\u00dferdem liegt im Landesinneren Valtura, wo Sie einige sch\u00f6ne H\u00fcgel finden werden. Diese liegen ein wenig weiter n\u00f6rdlich. Was auch cool ist: Bei Krnica geht es ziemlich direkt zum Meer hinunter. Es ist eine Einbahnstra\u00dfe, also muss man auch wieder hinauffahren. Ein bisschen wie Sa Calobra auf Mallorca, aber etwas anders. Mit 2,5 Kilometern auch viel k\u00fcrzer, aber mit l\u00e4ngeren Abschnitten \u00fcber 10%. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"2120\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/brijuni-ivo-biocina-1-1024x576.jpeg\" alt=\"\" class=\"wp-image-2120\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/brijuni-ivo-biocina-1-1024x576.jpeg 1024w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/brijuni-ivo-biocina-1-300x169.jpeg 300w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/brijuni-ivo-biocina-1-768x432.jpeg 768w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/brijuni-ivo-biocina-1-1536x864.jpeg 1536w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/brijuni-ivo-biocina-1.jpeg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Brijuni (c) Kroatien.hr<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"652\" data-id=\"2124\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/cik3_associated_02.jpeg\" alt=\"\" class=\"wp-image-2124\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/cik3_associated_02.jpeg 1024w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/cik3_associated_02-300x191.jpeg 300w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/cik3_associated_02-768x489.jpeg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Krnica<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Schotter-Tipp des Tages: Parenzana<\/h2>\n\n\n\n<p>Radfahren entlang alter Eisenbahnstrecken. Das kann man heute an vielen Orten machen. So auch in Istrien \u00fcber die Parenzana. Sie hat viel Geschichte, man kann von Triest in Italien aus starten und es gibt eigentlich wenig befestigte Stra\u00dfen. Toll also. Durch Ackerland, \u00fcber alte Br\u00fccken, Tunnels, Weinberge, Fernsichten und h\u00fcbsche D\u00f6rfer. <\/p>\n\n\n\n<p>Mit einem Wort: viel Spa\u00df. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-6 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"2117\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/Parenzana-photo-1a-1-1024x576.jpeg\" alt=\"\" class=\"wp-image-2117\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/Parenzana-photo-1a-1-1024x576.jpeg 1024w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/Parenzana-photo-1a-1-300x169.jpeg 300w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/Parenzana-photo-1a-1-768x432.jpeg 768w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/Parenzana-photo-1a-1-1536x864.jpeg 1536w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/Parenzana-photo-1a-1-2048x1152.jpeg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">(c) Parenzana.net<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">M\u00f6chten Sie mehr \u00fcber das Radfahren in Istrien erfahren?<\/h2>\n\n\n\n<p>Auf der Website der <a rel=\"noreferrer noopener\" href=\"https:\/\/croatia.hr\/en-GB\/experiences\/active\/cycling\/istria-region\" target=\"_blank\">Kroatischer Tourismus<\/a> Agentur finden Sie bereits viele Informationen \u00fcber alle Aktivit\u00e4ten in dieser Region. Sie k\u00f6nnen auch die Website von <a rel=\"noreferrer noopener\" href=\"https:\/\/www.parenzana.net\/en\" target=\"_blank\">Parenzana<\/a> finden Sie alle Informationen zu dieser Route. Au\u00dferdem ist die Website von <a href=\"https:\/\/www.istria-bike.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Istrien Fahrrad<\/a> wertvolle Informationen zu Unterk\u00fcnften, Hotels usw. Wir sagen: Tun Sie es!<\/p>\n\n\n\n<iframe src=\"https:\/\/www.komoot.com\/nl-nl\/tour\/2183787681\/embed?share_token=a4Sk228OzsqTVhOpusB178bwb4qtLsMSjOHMTjSnueysvyLfqE&#038;profile=1&#038;gallery=1\" width=\"100%\" height=\"600\" frameborder=\"0\" scrolling=\"no\"><\/iframe>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Fietsen in Europa is fantastisch. Fietsen in Kroatie en met name fietsen in Istri\u00eb is geen uitzondering. Want niet alleen vind je hoge bergen, schitterende afdalingen, kasseien, gravel, zeeroutes en meer. Je kunt elk jaargetijde genieten van verschillende regio&#8217;s en landschappen. Ongekend eigenlijk. Sommige bestemmingen zijn al compleet uitgespeeld. Alhoewel: is het mogelijk om in [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2100,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"iawp_total_views":1343,"footnotes":""},"categories":[30,8],"tags":[],"class_list":["post-2097","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kroatie","category-verhalen"],"acf":[],"featured_image_url":{"thumbnail":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/03_Vojak-iz-zraka-01-Alan-Caplar-dronom-150x150.jpg","medium":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/03_Vojak-iz-zraka-01-Alan-Caplar-dronom-300x147.jpg","medium_large":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/03_Vojak-iz-zraka-01-Alan-Caplar-dronom-768x376.jpg","large":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/03_Vojak-iz-zraka-01-Alan-Caplar-dronom-1024x501.jpg","1536x1536":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/03_Vojak-iz-zraka-01-Alan-Caplar-dronom.jpg","2048x2048":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/03_Vojak-iz-zraka-01-Alan-Caplar-dronom.jpg","trp-custom-language-flag":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/03_Vojak-iz-zraka-01-Alan-Caplar-dronom.jpg"},"post_author":"Sander","assigned_categories":"Kroati\u00eb, Verhalen","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fietsen in Istri\u00eb is jouw eerste stop in Kroati\u00eb - Cycling Destination<\/title>\n<meta name=\"description\" content=\"Fietsen in Kroati\u00eb is schitterend. Istrie is populair bij toeristen. Ga ji ook met ons mee op ontdekking in dit schitterende land?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingdestination.cc\/de\/verhalen\/fietsen-in-kroatie\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fietsen in Istri\u00eb is jouw eerste stop in Kroati\u00eb - Cycling Destination\" \/>\n<meta property=\"og:description\" content=\"Fietsen in Kroati\u00eb is schitterend. Istrie is populair bij toeristen. Ga ji ook met ons mee op ontdekking in dit schitterende land?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingdestination.cc\/de\/verhalen\/fietsen-in-kroatie\/\" \/>\n<meta property=\"og:site_name\" content=\"Cycling Destination\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cyclingdestination.cc\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-02T16:00:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-23T10:55:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/03_Vojak-iz-zraka-01-Alan-Caplar-dronom.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1140\" \/>\n\t<meta property=\"og:image:height\" content=\"558\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sander\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cyclingdestin\" \/>\n<meta name=\"twitter:site\" content=\"@cyclingdestin\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sander\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-kroatie#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-kroatie\"},\"author\":{\"name\":\"Sander\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#\\\/schema\\\/person\\\/c4e8c05a4462c13aab4450ec88e285ad\"},\"headline\":\"Fietsen in Istri\u00eb is jouw eerste stop in Kroati\u00eb\",\"datePublished\":\"2021-10-02T16:00:36+00:00\",\"dateModified\":\"2025-04-23T10:55:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-kroatie\"},\"wordCount\":1073,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-kroatie#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingdestination.cc\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/03_Vojak-iz-zraka-01-Alan-Caplar-dronom.jpg\",\"articleSection\":[\"Kroati\u00eb\",\"Verhalen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-kroatie#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-kroatie\",\"url\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-kroatie\",\"name\":\"Fietsen in Istri\u00eb is jouw eerste stop in Kroati\u00eb - Cycling Destination\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-kroatie#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-kroatie#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingdestination.cc\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/03_Vojak-iz-zraka-01-Alan-Caplar-dronom.jpg\",\"datePublished\":\"2021-10-02T16:00:36+00:00\",\"dateModified\":\"2025-04-23T10:55:24+00:00\",\"description\":\"Fietsen in Kroati\u00eb is schitterend. Istrie is populair bij toeristen. Ga ji ook met ons mee op ontdekking in dit schitterende land?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-kroatie#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-kroatie\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-kroatie#primaryimage\",\"url\":\"https:\\\/\\\/cyclingdestination.cc\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/03_Vojak-iz-zraka-01-Alan-Caplar-dronom.jpg\",\"contentUrl\":\"https:\\\/\\\/cyclingdestination.cc\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/03_Vojak-iz-zraka-01-Alan-Caplar-dronom.jpg\",\"width\":1140,\"height\":558,\"caption\":\"Ucka pass Croatia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-kroatie#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingdestination.cc\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fietsen in Istri\u00eb is jouw eerste stop in Kroati\u00eb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#website\",\"url\":\"https:\\\/\\\/cyclingdestination.cc\\\/\",\"name\":\"Cycling Destination\",\"description\":\"Inspiratie voor jouw volgende fietsavontuur\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingdestination.cc\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#organization\",\"name\":\"Cycling Destination\",\"url\":\"https:\\\/\\\/cyclingdestination.cc\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingdestination.cc\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/cyclingdestination_logo_RGB_zwart_vDEF-1.png\",\"contentUrl\":\"https:\\\/\\\/cyclingdestination.cc\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/cyclingdestination_logo_RGB_zwart_vDEF-1.png\",\"width\":2550,\"height\":814,\"caption\":\"Cycling Destination\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cyclingdestination.cc\",\"https:\\\/\\\/x.com\\\/cyclingdestin\",\"https:\\\/\\\/www.instagram.com\\\/cyclingdestination.cc\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#\\\/schema\\\/person\\\/c4e8c05a4462c13aab4450ec88e285ad\",\"name\":\"Sander\",\"url\":\"https:\\\/\\\/cyclingdestination.cc\\\/de\\\/author\\\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Radfahren in Istrien ist Ihr erster Halt in Kroatien - Cycling Destination","description":"Radfahren in Kroatien ist wunderbar. Istrien ist bei Touristen sehr beliebt. Wird ji auch mit uns dieses sch\u00f6ne Land erkunden?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingdestination.cc\/de\/verhalen\/fietsen-in-kroatie\/","og_locale":"de_DE","og_type":"article","og_title":"Fietsen in Istri\u00eb is jouw eerste stop in Kroati\u00eb - Cycling Destination","og_description":"Fietsen in Kroati\u00eb is schitterend. Istrie is populair bij toeristen. Ga ji ook met ons mee op ontdekking in dit schitterende land?","og_url":"https:\/\/cyclingdestination.cc\/de\/verhalen\/fietsen-in-kroatie\/","og_site_name":"Cycling Destination","article_publisher":"https:\/\/www.facebook.com\/cyclingdestination.cc","article_published_time":"2021-10-02T16:00:36+00:00","article_modified_time":"2025-04-23T10:55:24+00:00","og_image":[{"width":1140,"height":558,"url":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/03_Vojak-iz-zraka-01-Alan-Caplar-dronom.jpg","type":"image\/jpeg"}],"author":"Sander","twitter_card":"summary_large_image","twitter_creator":"@cyclingdestin","twitter_site":"@cyclingdestin","twitter_misc":{"Verfasst von":"Sander","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-kroatie#article","isPartOf":{"@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-kroatie"},"author":{"name":"Sander","@id":"https:\/\/cyclingdestination.cc\/#\/schema\/person\/c4e8c05a4462c13aab4450ec88e285ad"},"headline":"Fietsen in Istri\u00eb is jouw eerste stop in Kroati\u00eb","datePublished":"2021-10-02T16:00:36+00:00","dateModified":"2025-04-23T10:55:24+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-kroatie"},"wordCount":1073,"commentCount":2,"publisher":{"@id":"https:\/\/cyclingdestination.cc\/#organization"},"image":{"@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-kroatie#primaryimage"},"thumbnailUrl":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/03_Vojak-iz-zraka-01-Alan-Caplar-dronom.jpg","articleSection":["Kroati\u00eb","Verhalen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-kroatie#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-kroatie","url":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-kroatie","name":"Radfahren in Istrien ist Ihr erster Halt in Kroatien - Cycling Destination","isPartOf":{"@id":"https:\/\/cyclingdestination.cc\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-kroatie#primaryimage"},"image":{"@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-kroatie#primaryimage"},"thumbnailUrl":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/03_Vojak-iz-zraka-01-Alan-Caplar-dronom.jpg","datePublished":"2021-10-02T16:00:36+00:00","dateModified":"2025-04-23T10:55:24+00:00","description":"Radfahren in Kroatien ist wunderbar. Istrien ist bei Touristen sehr beliebt. Wird ji auch mit uns dieses sch\u00f6ne Land erkunden?","breadcrumb":{"@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-kroatie#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-kroatie"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-kroatie#primaryimage","url":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/03_Vojak-iz-zraka-01-Alan-Caplar-dronom.jpg","contentUrl":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2021\/10\/03_Vojak-iz-zraka-01-Alan-Caplar-dronom.jpg","width":1140,"height":558,"caption":"Ucka pass Croatia"},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-kroatie#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingdestination.cc\/"},{"@type":"ListItem","position":2,"name":"Fietsen in Istri\u00eb is jouw eerste stop in Kroati\u00eb"}]},{"@type":"WebSite","@id":"https:\/\/cyclingdestination.cc\/#website","url":"https:\/\/cyclingdestination.cc\/","name":"Ziel Radfahren","description":"Inspiration f\u00fcr Ihr n\u00e4chstes Fahrradabenteuer","publisher":{"@id":"https:\/\/cyclingdestination.cc\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingdestination.cc\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/cyclingdestination.cc\/#organization","name":"Ziel Radfahren","url":"https:\/\/cyclingdestination.cc\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cyclingdestination.cc\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/01\/cyclingdestination_logo_RGB_zwart_vDEF-1.png","contentUrl":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/01\/cyclingdestination_logo_RGB_zwart_vDEF-1.png","width":2550,"height":814,"caption":"Cycling Destination"},"image":{"@id":"https:\/\/cyclingdestination.cc\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cyclingdestination.cc","https:\/\/x.com\/cyclingdestin","https:\/\/www.instagram.com\/cyclingdestination.cc\/"]},{"@type":"Person","@id":"https:\/\/cyclingdestination.cc\/#\/schema\/person\/c4e8c05a4462c13aab4450ec88e285ad","name":"Sander","url":"https:\/\/cyclingdestination.cc\/de\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/posts\/2097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/comments?post=2097"}],"version-history":[{"count":0,"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/posts\/2097\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/media\/2100"}],"wp:attachment":[{"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/media?parent=2097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/categories?post=2097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/tags?post=2097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}