{"id":5247,"date":"2022-03-01T15:48:36","date_gmt":"2022-03-01T14:48:36","guid":{"rendered":"https:\/\/cyclingdestination.cc\/?p=5247"},"modified":"2025-12-21T12:00:15","modified_gmt":"2025-12-21T11:00:15","slug":"fietsen-op-gran-canaria-off-road","status":"publish","type":"post","link":"https:\/\/cyclingdestination.cc\/de\/verhalen\/fietsen-op-gran-canaria-off-road","title":{"rendered":"Radfahren auf Gran Canaria abseits der Stra\u00dfe: Teil 2"},"content":{"rendered":"<p><a href=\"http:\/\/www.instagram.com\/ruthkoopsvtj\" target=\"_blank\" rel=\"noreferrer noopener\">Ruth Koops van 't Jagt<\/a> war f\u00fcr unsere Plattform eine Woche auf den Kanarischen Inseln und zwar <a href=\"https:\/\/cutt.ly\/sArBDDU\" target=\"_blank\" rel=\"noreferrer noopener\">Gran Canaria<\/a>! Dass diese Insel eine wunderbare Flucht aus der Realit\u00e4t sein kann, zeigt der erste Teil ihres Berichts, der vor einiger Zeit auf Cycling Destination erschienen ist. Wieder gibt es tolle Tipps und Tricks. Diesmal sch\u00f6n abseits der Stra\u00dfe und sogar eine sch\u00f6ne Wanderung! Tja, manchmal muss man eben abseits der ausgetretenen Pfade denken. Wir sind total begeistert von dieser Insel und den M\u00f6glichkeiten zum Radfahren und Aktivsein. Schaut euch den Bericht unten an. Viel Spa\u00df beim Lesen! Radfahren auf Gran Canaria ist auch abseits der Stra\u00dfe sch\u00f6n! Lesen Sie die Fortsetzung dieses Artikels <a href=\"https:\/\/cyclingdestination.cc\/de\/verhalen\/spanje\/fietsavontuur-op-gran-canaria-deel-3\/\">Teil 2 hier<\/a> und lesen Sie den ersten Bericht <a href=\"https:\/\/cyclingdestination.cc\/de\/verhalen\/spanje\/fietsen-op-gran-canaria-de-winter-ontvluchten\/\">hier<\/a>!<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large is-style-default\"><img fetchpriority=\"high\" decoding=\"async\" width=\"2049\" height=\"1153\" data-id=\"5238\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/IMG_3312.jpg\" alt=\"Gran Canaria - Radfahren mit dem MTB\" class=\"wp-image-5238\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/IMG_3312.jpg 2049w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/IMG_3312-300x169.jpg 300w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/IMG_3312-1024x576.jpg 1024w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/IMG_3312-768x432.jpg 768w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/IMG_3312-1536x864.jpg 1536w\" sizes=\"(max-width: 2049px) 100vw, 2049px\" \/><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">MTB mit Santiago&nbsp;<\/h2>\n\n\n\n<p>Seit wir ins Flugzeug gestiegen sind, haben wir uns auf diesen Dienstag gefreut, mit den erwartungsvollen Schmetterlingen, die man als Kind vor seinem Geburtstag versp\u00fcrt. In den Niederlanden bezwingen wir die Anstiege und Singletracks der Gieten Gasselte gemeinsam auf dem MTB. Also auf unserer Wunschliste f\u00fcr <a href=\"https:\/\/cyclingdestination.cc\/de\/verhalen\/spanje\/fietsen-op-gran-canaria-de-winter-ontvluchten\/\">Gran Canaria<\/a> stand mindestens eine sch\u00f6ne Mountainbiketour, am besten mit einem F\u00fchrer. Wir wissen noch wenig dar\u00fcber, was uns genau erwartet, also haben wir Santiago per App gewarnt.  Wir sind wirklich Freizeitradler\", schicken wir ihm. Zum Gl\u00fcck bekamen wir beruhigende Worte zur\u00fcck: 'Keine Sorge. Die Strecke ist nicht schwer. Wir werden zuerst hinunterfahren und dann leicht hinauffahren. Wenn ihr m\u00fcde werdet, werde ich euch erholen.' Das macht einen Unterschied.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large is-style-default\"><img decoding=\"async\" width=\"1985\" height=\"1116\" data-id=\"5271\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/IMG_3304.jpg\" alt=\"Kim und Ruth beim Radfahren auf Gran Canaria\" class=\"wp-image-5271\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/IMG_3304.jpg 1985w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/IMG_3304-300x169.jpg 300w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/IMG_3304-1024x576.jpg 1024w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/IMG_3304-768x432.jpg 768w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/IMG_3304-1536x864.jpg 1536w\" sizes=\"(max-width: 1985px) 100vw, 1985px\" \/><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Sammeldienst<\/h2>\n\n\n\n<p>Kurz nach 9 Uhr holt uns Santiago mit seinem Lieferwagen vor Dunas ab, die Mountainbikes bereits im Kofferraum. In etwas mehr als einer Stunde fahren wir \u00fcber kurvenreiche Stra\u00dfen und vorbei an bl\u00fchenden Mandelb\u00e4umen zu seinem \"Landhaus\" Finca Nido de Aguilas, was so viel hei\u00dft wie Adlernest. Das Haus liegt auf mehr als 1.500 Metern H\u00f6he in der N\u00e4he des hochgelegenen Cruz de Tejeda und wurde einst von seinem Vater und Gro\u00dfvater gebaut. Vorne im Auto sehen wir, wie die Au\u00dfentemperatur von 25 Grad an der K\u00fcste auf l\u00e4ppische 12 Grad in den Bergen f\u00e4llt. Und dann weht auch noch ein st\u00fcrmischer Calima-Wind. Als wir aus dem Auto aussteigen, wird uns sofort klar, dass wir neben Helm, Sonnenbrille und Culotte\" auch eine Jacke oder zumindest Armstulpen h\u00e4tten mitnehmen sollen. Zum Gl\u00fcck hat Santiago noch ein paar Ersatzklamotten dabei und etwas besser eingepackt starten wir den ersten Teil der Strecke.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large is-style-default\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"5261\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/d80d5ee6-ce7c-4a63-8ed8-04fd4d8a106e-1024x576.jpg\" alt=\"\" class=\"wp-image-5261\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/d80d5ee6-ce7c-4a63-8ed8-04fd4d8a106e-1024x576.jpg 1024w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/d80d5ee6-ce7c-4a63-8ed8-04fd4d8a106e-300x169.jpg 300w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/d80d5ee6-ce7c-4a63-8ed8-04fd4d8a106e-768x432.jpg 768w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/d80d5ee6-ce7c-4a63-8ed8-04fd4d8a106e-1536x864.jpg 1536w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/d80d5ee6-ce7c-4a63-8ed8-04fd4d8a106e.jpg 1559w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Atemberaubende Aussichten<\/h2>\n\n\n\n<p>Nach einem kurzen Auf- und Abstieg kommen wir an einem atemberaubenden Aussichtspunkt vorbei. Der Wind bl\u00e4st hier so stark, dass ich (mit <a href=\"https:\/\/www.ruthkoopsvantjagt.nl\/2020\/08\/20\/de-banden-vol-met-wind-en-een-hart-vol-met-angst-een-confrontatie-met-de-mont-ventoux-2\/\" target=\"_blank\" rel=\"noreferrer noopener\">Windtrauma<\/a> der <a href=\"https:\/\/cyclingdestination.cc\/de\/classic-rides\/classic-ride-de-mont-ventoux\/\">Mont Ventoux<\/a>), der meinen Helm festh\u00e4lt. An einem klaren Tag kann man den Teide von hier aus sehen <a href=\"https:\/\/cyclingdestination.cc\/de\/verhalen\/winterbestemming-tenerife-meer-dan-el-teide\/\">Teneriffa<\/a> aber in den letzten Wochen hat der Calima zu viel Staub in die Atmosph\u00e4re geblasen. Das ist uns egal. <\/p>\n\n\n\n<p>Nach etwa f\u00fcnf Kilometern verlassen wir den Asphalt und tauchen in einen Wald ein: den Pinienwald Pinos de G\u00e1ldar. Der Weg dorthin steigt fast sofort steil an, aber zum Gl\u00fcck \"rettet\" mich meine Kette, als sie im letzten Gang abspringt. Das gibt uns Zeit, unseren Mut zu sammeln. Santiago informiert uns \u00fcber die einheimische Flora und zeigt uns u.a. die Pflanzenarten Tajinastes, Tabaias, Mirtillo, Retamas und Cobezos. W\u00e4hrend Santiago dann routinem\u00e4\u00dfig meine Kette wieder anbringt, klettert Kim voraus. Ich folge kurz darauf auf dem Ein-Licht-Widerstand.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"5262\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/IMG_3454-1024x576.jpg\" alt=\"\" class=\"wp-image-5262\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/IMG_3454-1024x576.jpg 1024w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/IMG_3454-300x169.jpg 300w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/IMG_3454-768x432.jpg 768w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/IMG_3454-1536x864.jpg 1536w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/IMG_3454-2048x1152.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Weiter oben<\/h3>\n\n\n\n<p>Das ist f\u00fcr mich die beste Art des Radfahrens auf Gran Canaria: auf Waldwegen klettern und die Felsen hinaufst\u00fcrmen, umgeben von hohen Pinienb\u00e4umen. Au\u00dfer Atem, aber mit der auf unbefestigten Wegen so notwendigen Konzentration. Auf dem Gipfel des kurzen Anstiegs erwartet mich Kim l\u00e4chelnd, weil sie denkt, dass wir erst auf halbem Weg sind. Aber es stellt sich heraus, dass wir von hier aus bereits absteigen d\u00fcrfen. Durch den Kiefernwald\" folgt eine sch\u00f6ne, lange, h\u00fcgelige Abfahrt. Die ersten Abschnitte sind etwas steiler, aber auch f\u00fcr uns Amateure machbar. Konzentriert h\u00fcpfen wir \u00fcber die Felsen und \u00fcben unsere \"Klavierfinger\". Laut Santiago ist das die Art und Weise, wie man absteigt, ohne Kr\u00e4mpfe in den H\u00e4nden zu bekommen. Er lehrt uns auch, dass es entgegen unserer Intuition besser ist, etwas schneller abzusteigen, denn das ist tats\u00e4chlich einfacher als langsam und vorsichtig.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"5263\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/IMG_3361-1024x1024.jpg\" alt=\"\" class=\"wp-image-5263\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/IMG_3361-1024x1024.jpg 1024w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/IMG_3361-300x300.jpg 300w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/IMG_3361-150x150.jpg 150w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/IMG_3361-768x768.jpg 768w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/IMG_3361.jpg 1537w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>Lesen Sie auch:<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-cycling-destination wp-block-embed-cycling-destination\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"nnMFS9saC6\"><a href=\"https:\/\/cyclingdestination.cc\/de\/verhalen\/spanje\/fietsen-op-gran-canaria-de-winter-ontvluchten\/\">Radfahren auf Gran Canaria: der ultimative Ort, um dem Winter zu entfliehen<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"\u201cRadfahren auf Gran Canaria: der ultimative Ort, um dem Winter zu entfliehen\u201d - Cycling Destination\" src=\"https:\/\/cyclingdestination.cc\/verhalen\/spanje\/fietsen-op-gran-canaria-de-winter-ontvluchten\/embed#?secret=JWsGsudG8V#?secret=nnMFS9saC6\" data-secret=\"nnMFS9saC6\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Ein kurzer Aufstieg f\u00fcr die Aussicht<\/h3>\n\n\n\n<p>Nach dem ersten Teil des Abstiegs tritt Santiago auf die Bremse, steigt von seinem Fahrrad ab und stellt es an einen Felsen. Hier, auf der anderen Seite der Klippe, entpuppt sich eine besondere H\u00f6hle: Cuevas de Caballero o de Las Machas. Macha\" bedeutet \"Frau, die wie ein Mann aussieht\". <\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Ihm folgen<\/h4>\n\n\n\n<p>Kim klettert furchtlos hinter Santiago um die Ecke, aber mein Windtrauma h\u00e4lt mich f\u00fcr eine Weile zur\u00fcck. Ich schlucke ein paar Mal: Ich werde nicht zulassen, dass diese bl\u00f6de Angst mich um dieses Erlebnis bringt. Fu\u00df f\u00fcr Fu\u00df schlurfe ich um die Ecke, so nah an den Felsen wie m\u00f6glich. Der Wind pfeift mir um die Ohren. Auf der anderen Seite angekommen, haben wir einen herrlichen Blick auf die Berge und das Tal. Santiago zeigt uns die H\u00f6hle, in der wir sogar einige alte Wandmalereien entdecken. Wir klettern weiter \u00fcber die Felsen und genie\u00dfen das schimmernde Panorama der Caldera de Tejeda. Gran Canaria ist fantastisch.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-6 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"5254\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/129da9fe-09f3-4aa0-a064-642b6f7595f7-1024x576.jpg\" alt=\"Dies sind nur Ansichten und solche, die man sieht, wenn man mit dem Fahrrad im Gel\u00e4nde unterwegs ist\" class=\"wp-image-5254\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/129da9fe-09f3-4aa0-a064-642b6f7595f7-1024x576.jpg 1024w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/129da9fe-09f3-4aa0-a064-642b6f7595f7-300x169.jpg 300w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/129da9fe-09f3-4aa0-a064-642b6f7595f7-768x432.jpg 768w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/129da9fe-09f3-4aa0-a064-642b6f7595f7-1536x864.jpg 1536w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/129da9fe-09f3-4aa0-a064-642b6f7595f7.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Die Aussicht ist fast surreal<\/figcaption><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Keine Teeparty<\/h3>\n\n\n\n<p>Dann wird Santiago ungeduldig. Wir k\u00f6nnen fast h\u00f6ren, wie er denkt: \"Das ist eine Radtour, meine Damen, keine Teeparty! In der Zwischenzeit steigen wir wieder auf unsere R\u00e4der und beginnen den zweiten Teil des Abstiegs. Wie ge\u00fcbte Abfahrer fliegen wir \"piano fingers, piano fingers!\" zwischen den B\u00e4umen hindurch, bis wir wieder eine asphaltierte Stra\u00dfe erreichen. Dann sind es nur noch wenige Kilometer, bis wir in das sch\u00f6ne Dorf Artenara radeln. Artenara ist das h\u00f6chstgelegene Dorf auf Gran Canaria, 1270 Meter \u00fcber dem Meeresspiegel. Empfangen werden wir von einer Christusstatue mit ausgebreiteten Armen. Im Dorf finden wir au\u00dferdem eine modernere Fahrradstatue, mit der wir nat\u00fcrlich ein Foto machen. Santiago bringt uns auch zum Unamuno-Aussichtspunkt, von dem aus man einen spektakul\u00e4ren Blick hat. <\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Miquel de Unamuno<\/h4>\n\n\n\n<p>Miquel de Unamuno, ein ber\u00fchmter Schriftsteller und Philosoph, hielt sich 1910 auf der Insel auf und beschrieb die zerkl\u00fcftete Landschaft mit den Worten \"versteinerter Sturm\". In den Tiefen der Insel gibt es auch eine fantastisch sch\u00f6ne MTB-Strecke. Dieses sch\u00f6ne Dorf ist ein guter Ort f\u00fcr einen Zwischenstopp, und in dem kleinen Caf\u00e9 Arte-Gaia Restaurante BioTasca m\u00fcssen wir unbedingt Santagia caf\u00e9 con leche und Churros probieren. Der Kaffee wird in gro\u00dfen Tassen serviert, und der Besitzer zeigt uns eindringlich, wie man die Churros anschlie\u00dfend in den Kaffee taucht.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-7 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"379\" data-id=\"5259\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/788d742b-871c-4e9f-bc7f-cd67348e16ec-1024x379.jpg\" alt=\"\" class=\"wp-image-5259\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/788d742b-871c-4e9f-bc7f-cd67348e16ec-1024x379.jpg 1024w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/788d742b-871c-4e9f-bc7f-cd67348e16ec-300x111.jpg 300w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/788d742b-871c-4e9f-bc7f-cd67348e16ec-768x284.jpg 768w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/788d742b-871c-4e9f-bc7f-cd67348e16ec-1536x568.jpg 1536w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/788d742b-871c-4e9f-bc7f-cd67348e16ec.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Zur\u00fcck nach Hause <\/h2>\n\n\n\n<p>Wir essen auch heimlich eine Banane und bereiten uns auf die R\u00fcckfahrt vor. Jetzt kommt der kniffligste Teil der Strecke, mit den meisten Steigungskilometern. Aber zum Gl\u00fcck \u00fcbersteigt die Steigung nirgends 9%. Das sollte machbar sein. Bevor wir den R\u00fcckweg antreten, werfen wir noch einen Blick auf ein Restaurant, das ebenfalls in die Felswand gehauen zu sein scheint. Wohin man hier auch schaut, die Aussicht ist atemberaubend. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-8 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"5269\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/IMG_3378-1024x576.jpg\" alt=\"\" class=\"wp-image-5269\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/IMG_3378-1024x576.jpg 1024w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/IMG_3378-300x169.jpg 300w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/IMG_3378-768x432.jpg 768w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/IMG_3378-1536x864.jpg 1536w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>Ein letzter Blick zur\u00fcck, dann geht es weiter f\u00fcr die letzten Kilometer. Am Rad von Santiago. Wir finden beide unseren eigenen Rhythmus. \u00dcber die GC-21 schl\u00e4ngeln wir uns wieder bergauf. Nach den steilsten Kilometern steuert Santiago sein Rad bei etwa 1.500 Metern auf den Seitenstreifen. Er l\u00e4sst die kleinen schwarzen Kieselsteine durch seine H\u00e4nde gleiten: \"Das nennen wir Pic\u00f3n, das ist Vulkanasche! Pic\u00f3n ist eines von vielen W\u00f6rtern auf den Kanarischen Inseln, die ihren Ursprung in der vulkanischen Natur dieses Archipels haben. Eine nat\u00fcrliche Quelle scheint aus den Felsen zu sprudeln. Wir machen eine Schale aus unseren H\u00e4nden und trinken das frische Bergwasser.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Route<\/h2>\n\n\n\n<iframe src=\"https:\/\/www.komoot.nl\/tour\/687524478\/embed?profile=1\" width=\"100%\" height=\"680\" frameborder=\"0\" scrolling=\"no\"><\/iframe>\n\n\n\n<h2 class=\"wp-block-heading\">Letzte Etappe<\/h2>\n\n\n\n<p>Erfrischt und gest\u00e4rkt f\u00fcllen wir unsere Wasserflaschen auf und beginnen die letzte Etappe. Wir halten noch einmal am Mirador de Pinos de Caldar an, von wo aus man einen tollen Blick auf den Krater eines erloschenen Vulkans hat. Und dann ist es wirklich Zeit f\u00fcr die letzten Kilometer. Kurz bevor wir die supersteile Auffahrt zum Haus erreichen, warnt uns Santiago: \"Leichtester Gang! Kim tanzt auf den Pedalen bergauf, aber ich verschlucke mich an diesem letzten St\u00fcck. Mit dem Fahrrad in der Hand absolviere ich die letzten Meter bis zum Tor. Dort steht Santiago mit frisch gepfl\u00fcckten Osterglocken bereit. Wir f\u00fchlen uns wie echte Etappensieger. Nur die Rondemisters fehlen noch. Was f\u00fcr eine wunderbare Fahrt und wie sehr wir sie genossen haben. Mit einem breiten Grinsen steigen wir in den Van f\u00fcr die R\u00fcckfahrt nach Maspalomas. Wir schauen uns an: 'Morgen ein Ruhetag? Ja, morgen ist ein Ruhetag!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Tag 5 - Wie aus einem Ruhetag doch kein Ruhetag wurde&nbsp;<\/h2>\n\n\n\n<p>Obwohl wir gestern noch dachten, dass wir heute einen Ruhetag einlegen w\u00fcrden, haben die wundersch\u00f6nen Berge im Zentrum Gran Canarias unsere Herzen erobert. Wir wollen zur\u00fcck, beschlie\u00dfen wir, und dann machen wir einen \"Fahrrad-Ruhetag\" und schn\u00fcren unsere Wanderschuhe. Bei der Autovermietung in Dunas (Lucas Rent a Car) mieten wir das allerletzte verf\u00fcgbare Auto an diesem Tag: einen Mini Cooper Cabrio. Kim klettert hinter das Steuer, Tim setzt sich neben sie und ich setze mich auf den R\u00fccksitz. Wir setzen unsere Sonnenbrillen auf und fahren los. Wir f\u00fchlen uns wie echte Filmstars, als wir mit offenem Dach durch Maspalomas fahren. Filmstars in einem Film \u00fcber Bergwanderer, meine ich. Santiago hat uns gestern einige Tipps f\u00fcr tolle Wanderrouten gegeben. Wir fahren auf der GC-60 nach Norden zu den Llanos de La Pez, einem Naherholungsgebiet mit Picknickpl\u00e4tzen, vielen Parkpl\u00e4tzen und dem Startpunkt einiger sch\u00f6ner Wanderwege.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Beginn der Route<\/h2>\n\n\n\n<p>Hier beginnen wir den ersten Teil unserer Wanderroute, die uns zum ber\u00fchmten Pico de las Nieves f\u00fchrt. Dieser ist mit 1949 Metern der zweith\u00f6chste Berg auf Gran Canaria. Durch einen Kiefernwald folgen wir den steilen Pfaden nach oben, Kim mit professioneller Wanderausr\u00fcstung inklusive Wanderst\u00f6cken und Tim mit einem abgebrochenen Ast als Wanderstock. Um uns herum sehen wir, dass die Unterseite vieler Baumst\u00e4mme geschw\u00e4rzt ist. Hier hat es vor einiger Zeit Waldbr\u00e4nde gegeben. Zum Gl\u00fcck ist die <em>Kanaren-Kiefer (Pinus canariensis)<\/em>oder Kanarische Kiefer, einer der waldbrandresistentesten B\u00e4ume \u00fcberhaupt.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Felsen hoch<\/h2>\n\n\n\n<p>Als wir uns dem Pico n\u00e4hern, ver\u00e4ndert sich die Landschaft, und wir klettern das letzte St\u00fcck \u00fcber felsiges Gel\u00e4nde hinauf. Oben angekommen, klettern wir auf eine Aussichtsplattform, um uns f\u00fcr einen Moment als \"K\u00f6nig der Welt\" zu f\u00fchlen. Dann g\u00f6nnen wir uns Kaffee, Cola und frische Mandarinen aus dem Imbisswagen, der auf dem Parkplatz in der N\u00e4he des Gipfels steht. Wir sehen mehrere Radfahrer, die mit dem Fahrrad auf den Gipfel fahren und die \u00fcblichen \"Gipfelselfies\" machen, um dann wieder umzukehren. Normalerweise kann man von hier aus auch wieder den Teide von Teneriffa sehen, aber es ist ein bew\u00f6lkter und windiger Tag, so dass es heute nur verh\u00fcllte Bergspitzen bleiben. Gl\u00fccklicherweise sind auch diese Aussichten sehr sch\u00f6n, und wir sehen den Monolithen Roque Nublo (Fels in den Wolken), eine charakteristische gro\u00dfe Felsformation und der dritth\u00f6chste Punkt der Insel.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Zwischenstopp<\/h3>\n\n\n\n<p>Nach unserem Zwischenstopp steigen wir in dieselbe Richtung ab, um dann weiter in Richtung Degollada de los Hornos und El Monta\u00f1\u00f3n zu wandern. Wir wandern auf einem schmalen Grat und klettern mit H\u00e4nden und F\u00fc\u00dfen einen felsigen Hang hinauf, vorbei an den ber\u00fchmtesten Gipfeln Gran Canarias: dem Roque Nublo, El Fraile (ein Felsen, der wie ein M\u00f6nch aussieht) und La Rana (der Felsen daneben, der wie ein Frosch aussieht). <\/p>\n\n\n\n<p>Der letzte Abschnitt der Route verl\u00e4uft entlang des Stausees Presas de los Hornos. Es ist ein sch\u00f6ner Wanderweg, der manchmal regelrechtes Klettern \u00fcber Felsen erfordert. Die Aussichten sind atemberaubend, die Abstiege auf losem Schotter manchmal t\u00fcckisch und unsere Waden scheinen mit jedem Schritt st\u00e4rker zu werden. Nach mehr als 11 Kilometern und \u00fcber 500 H\u00f6henmetern, die wir durch die Berge gewandert sind, kommen wir wieder am Ausgangspunkt an. Wir lassen uns auf die Sitze unseres Mini Cooper sinken und schauen uns mit einem breiten, m\u00fcden L\u00e4cheln an. Es war zwar kein Ruhetag, aber ein verdammt guter.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ruhetag - Wandertag<\/h2>\n\n\n\n<p>Wenn Sie auf Gran Canaria mit dem Fahrrad unterwegs sind, empfehlen wir Ihnen, Ihr Fahrrad f\u00fcr einen Tag stehen zu lassen und Ihre Wanderschuhe anzuziehen. So kommen Sie an Orte, die Sie mit dem Mountainbike gar nicht erreichen w\u00fcrden, und erleben die fantastische Bergwelt Gran Canarias auf eine andere Art. Aber morgen nehmen wir wieder das Fahrrad. Tim wird morgen von Maspalomas aus das Zentrum der Insel erkunden und plant eine Strecke von mehr als 100 Kilometern. Wir entscheiden uns f\u00fcr die \u00fcberschaubare Variante und \u00fcberlegen, wie wir uns und unsere R\u00e4der nach Ayacata bringen k\u00f6nnen. Laut Santiago ist Ayacata ein perfekter Ausgangspunkt f\u00fcr eine sch\u00f6ne Strecke mit einigen H\u00f6henmetern im sch\u00f6nen Zentrum der Insel. Aber erst einmal: essen, trinken und schlafen.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Hoteltipps auf Gran Canaria<\/h2>\n\n\n\n<iframe id=\"stay22-widget\" width=\"100%\" height=\"428\" src=\"https:\/\/www.stay22.com\/embed\/6947b69367173ecf38777457\" frameborder=\"0\"><\/iframe>","protected":false},"excerpt":{"rendered":"<p>Ruth Koops van &#8217;t Jagt was voor ons platform een week op de Canarische Eilanden en dan specifiek Gran Canaria! Dat dit eiland een schitterende escape from reality kan zijn, dat blijkt wel uit het eerste deel van haar verslag, dat even geleden op Cycling Destination verscheen. Ook nu weer staan er mooie tips en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5254,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"iawp_total_views":238,"footnotes":""},"categories":[294,118,404,13,8],"tags":[68,177,75,72,67],"class_list":["post-5247","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-canarische-eilanden","category-gravel","category-mountainbiken","category-spanje","category-verhalen","tag-fietsreis","tag-gran-canaria","tag-gravel","tag-klimmen","tag-spanje"],"acf":[],"featured_image_url":{"thumbnail":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/129da9fe-09f3-4aa0-a064-642b6f7595f7-150x150.jpg","medium":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/129da9fe-09f3-4aa0-a064-642b6f7595f7-300x169.jpg","medium_large":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/129da9fe-09f3-4aa0-a064-642b6f7595f7-768x432.jpg","large":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/129da9fe-09f3-4aa0-a064-642b6f7595f7-1024x576.jpg","1536x1536":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/129da9fe-09f3-4aa0-a064-642b6f7595f7-1536x864.jpg","2048x2048":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/129da9fe-09f3-4aa0-a064-642b6f7595f7.jpg","trp-custom-language-flag":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/129da9fe-09f3-4aa0-a064-642b6f7595f7.jpg"},"post_author":"Sander","assigned_categories":"Canarische Eilanden, Gravel, Mountainbiken, Spanje, Verhalen","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fietsen op Gran Canaria off-road: deel 2 - Cycling Destination<\/title>\n<meta name=\"description\" content=\"Fietsen op Gran Canaria off road is prachtig, zoals dit verslag van Ruth Koops van &#039;t Jagt laat zien. Lees in deel 2 over de mogelijkheden!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingdestination.cc\/de\/verhalen\/fietsen-op-gran-canaria-off-road\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fietsen op Gran Canaria off-road: deel 2 - Cycling Destination\" \/>\n<meta property=\"og:description\" content=\"Fietsen op Gran Canaria off road is prachtig, zoals dit verslag van Ruth Koops van &#039;t Jagt laat zien. Lees in deel 2 over de mogelijkheden!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingdestination.cc\/de\/verhalen\/fietsen-op-gran-canaria-off-road\/\" \/>\n<meta property=\"og:site_name\" content=\"Cycling Destination\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cyclingdestination.cc\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-01T14:48:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-21T11:00:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/129da9fe-09f3-4aa0-a064-642b6f7595f7.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sander\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cyclingdestin\" \/>\n<meta name=\"twitter:site\" content=\"@cyclingdestin\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sander\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"13\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-op-gran-canaria-off-road#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-op-gran-canaria-off-road\"},\"author\":{\"name\":\"Sander\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#\\\/schema\\\/person\\\/c4e8c05a4462c13aab4450ec88e285ad\"},\"headline\":\"Fietsen op Gran Canaria off-road: deel 2\",\"datePublished\":\"2022-03-01T14:48:36+00:00\",\"dateModified\":\"2025-12-21T11:00:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-op-gran-canaria-off-road\"},\"wordCount\":2147,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-op-gran-canaria-off-road#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingdestination.cc\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/129da9fe-09f3-4aa0-a064-642b6f7595f7.jpg\",\"keywords\":[\"fietsreis\",\"gran canaria\",\"gravel\",\"klimmen\",\"spanje\"],\"articleSection\":[\"Canarische Eilanden\",\"Gravel\",\"Mountainbiken\",\"Spanje\",\"Verhalen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-op-gran-canaria-off-road#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-op-gran-canaria-off-road\",\"url\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-op-gran-canaria-off-road\",\"name\":\"Fietsen op Gran Canaria off-road: deel 2 - Cycling Destination\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-op-gran-canaria-off-road#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-op-gran-canaria-off-road#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingdestination.cc\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/129da9fe-09f3-4aa0-a064-642b6f7595f7.jpg\",\"datePublished\":\"2022-03-01T14:48:36+00:00\",\"dateModified\":\"2025-12-21T11:00:15+00:00\",\"description\":\"Fietsen op Gran Canaria off road is prachtig, zoals dit verslag van Ruth Koops van 't Jagt laat zien. Lees in deel 2 over de mogelijkheden!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-op-gran-canaria-off-road#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-op-gran-canaria-off-road\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-op-gran-canaria-off-road#primaryimage\",\"url\":\"https:\\\/\\\/cyclingdestination.cc\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/129da9fe-09f3-4aa0-a064-642b6f7595f7.jpg\",\"contentUrl\":\"https:\\\/\\\/cyclingdestination.cc\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/129da9fe-09f3-4aa0-a064-642b6f7595f7.jpg\",\"width\":1600,\"height\":900,\"caption\":\"uitzicht op Tenerife\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-op-gran-canaria-off-road#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingdestination.cc\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fietsen op Gran Canaria off-road: deel 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#website\",\"url\":\"https:\\\/\\\/cyclingdestination.cc\\\/\",\"name\":\"Cycling Destination\",\"description\":\"Inspiratie voor jouw volgende fietsavontuur\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingdestination.cc\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#organization\",\"name\":\"Cycling Destination\",\"url\":\"https:\\\/\\\/cyclingdestination.cc\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingdestination.cc\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/cyclingdestination_logo_RGB_zwart_vDEF-1.png\",\"contentUrl\":\"https:\\\/\\\/cyclingdestination.cc\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/cyclingdestination_logo_RGB_zwart_vDEF-1.png\",\"width\":2550,\"height\":814,\"caption\":\"Cycling Destination\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cyclingdestination.cc\",\"https:\\\/\\\/x.com\\\/cyclingdestin\",\"https:\\\/\\\/www.instagram.com\\\/cyclingdestination.cc\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#\\\/schema\\\/person\\\/c4e8c05a4462c13aab4450ec88e285ad\",\"name\":\"Sander\",\"url\":\"https:\\\/\\\/cyclingdestination.cc\\\/de\\\/author\\\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Radfahren auf Gran Canaria abseits der Stra\u00dfe: Teil 2 - Cycling Destination","description":"Radfahren auf Gran Canaria abseits der Stra\u00dfe ist wunderbar, wie dieser Bericht von Ruth Koops van 't Jagt zeigt. Lesen Sie \u00fcber die M\u00f6glichkeiten in Teil 2!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingdestination.cc\/de\/verhalen\/fietsen-op-gran-canaria-off-road\/","og_locale":"de_DE","og_type":"article","og_title":"Fietsen op Gran Canaria off-road: deel 2 - Cycling Destination","og_description":"Fietsen op Gran Canaria off road is prachtig, zoals dit verslag van Ruth Koops van 't Jagt laat zien. Lees in deel 2 over de mogelijkheden!","og_url":"https:\/\/cyclingdestination.cc\/de\/verhalen\/fietsen-op-gran-canaria-off-road\/","og_site_name":"Cycling Destination","article_publisher":"https:\/\/www.facebook.com\/cyclingdestination.cc","article_published_time":"2022-03-01T14:48:36+00:00","article_modified_time":"2025-12-21T11:00:15+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/129da9fe-09f3-4aa0-a064-642b6f7595f7.jpg","type":"image\/jpeg"}],"author":"Sander","twitter_card":"summary_large_image","twitter_creator":"@cyclingdestin","twitter_site":"@cyclingdestin","twitter_misc":{"Verfasst von":"Sander","Gesch\u00e4tzte Lesezeit":"13\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-op-gran-canaria-off-road#article","isPartOf":{"@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-op-gran-canaria-off-road"},"author":{"name":"Sander","@id":"https:\/\/cyclingdestination.cc\/#\/schema\/person\/c4e8c05a4462c13aab4450ec88e285ad"},"headline":"Fietsen op Gran Canaria off-road: deel 2","datePublished":"2022-03-01T14:48:36+00:00","dateModified":"2025-12-21T11:00:15+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-op-gran-canaria-off-road"},"wordCount":2147,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingdestination.cc\/#organization"},"image":{"@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-op-gran-canaria-off-road#primaryimage"},"thumbnailUrl":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/129da9fe-09f3-4aa0-a064-642b6f7595f7.jpg","keywords":["fietsreis","gran canaria","gravel","klimmen","spanje"],"articleSection":["Canarische Eilanden","Gravel","Mountainbiken","Spanje","Verhalen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingdestination.cc\/verhalen\/fietsen-op-gran-canaria-off-road#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-op-gran-canaria-off-road","url":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-op-gran-canaria-off-road","name":"Radfahren auf Gran Canaria abseits der Stra\u00dfe: Teil 2 - Cycling Destination","isPartOf":{"@id":"https:\/\/cyclingdestination.cc\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-op-gran-canaria-off-road#primaryimage"},"image":{"@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-op-gran-canaria-off-road#primaryimage"},"thumbnailUrl":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/129da9fe-09f3-4aa0-a064-642b6f7595f7.jpg","datePublished":"2022-03-01T14:48:36+00:00","dateModified":"2025-12-21T11:00:15+00:00","description":"Radfahren auf Gran Canaria abseits der Stra\u00dfe ist wunderbar, wie dieser Bericht von Ruth Koops van 't Jagt zeigt. Lesen Sie \u00fcber die M\u00f6glichkeiten in Teil 2!","breadcrumb":{"@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-op-gran-canaria-off-road#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingdestination.cc\/verhalen\/fietsen-op-gran-canaria-off-road"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-op-gran-canaria-off-road#primaryimage","url":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/129da9fe-09f3-4aa0-a064-642b6f7595f7.jpg","contentUrl":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/03\/129da9fe-09f3-4aa0-a064-642b6f7595f7.jpg","width":1600,"height":900,"caption":"uitzicht op Tenerife"},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-op-gran-canaria-off-road#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingdestination.cc\/"},{"@type":"ListItem","position":2,"name":"Fietsen op Gran Canaria off-road: deel 2"}]},{"@type":"WebSite","@id":"https:\/\/cyclingdestination.cc\/#website","url":"https:\/\/cyclingdestination.cc\/","name":"Ziel Radfahren","description":"Inspiration f\u00fcr Ihr n\u00e4chstes Fahrradabenteuer","publisher":{"@id":"https:\/\/cyclingdestination.cc\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingdestination.cc\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/cyclingdestination.cc\/#organization","name":"Ziel Radfahren","url":"https:\/\/cyclingdestination.cc\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cyclingdestination.cc\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/01\/cyclingdestination_logo_RGB_zwart_vDEF-1.png","contentUrl":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/01\/cyclingdestination_logo_RGB_zwart_vDEF-1.png","width":2550,"height":814,"caption":"Cycling Destination"},"image":{"@id":"https:\/\/cyclingdestination.cc\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cyclingdestination.cc","https:\/\/x.com\/cyclingdestin","https:\/\/www.instagram.com\/cyclingdestination.cc\/"]},{"@type":"Person","@id":"https:\/\/cyclingdestination.cc\/#\/schema\/person\/c4e8c05a4462c13aab4450ec88e285ad","name":"Sander","url":"https:\/\/cyclingdestination.cc\/de\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/posts\/5247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/comments?post=5247"}],"version-history":[{"count":1,"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/posts\/5247\/revisions"}],"predecessor-version":[{"id":25700,"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/posts\/5247\/revisions\/25700"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/media\/5254"}],"wp:attachment":[{"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/media?parent=5247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/categories?post=5247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/tags?post=5247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}