{"id":7571,"date":"2022-06-28T07:09:22","date_gmt":"2022-06-28T07:09:22","guid":{"rendered":"https:\/\/cyclingdestination.cc\/?p=7571"},"modified":"2022-07-02T09:27:29","modified_gmt":"2022-07-02T09:27:29","slug":"fietsen-in-noord-griekenland-van-florina-naar-nimfeio","status":"publish","type":"post","link":"https:\/\/cyclingdestination.cc\/de\/verhalen\/fietsen-in-noord-griekenland-van-florina-naar-nimfeio","title":{"rendered":"Radfahren in Nordgriechenland: von Florina nach Nimfeio"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Kaffee ist der Motor der griechischen Morgengesellschaft. Niemand macht sich ohne Kaffee auf den Weg. Auf dem Weg nach Kastoria habe ich sogar einen echten 'Coffee-drive-in' gesehen. Selbst f\u00fcr die Niederlande, wo man bei jedem Treffen Kaffee trinkt, ist das ein Schritt zu weit. Hier trinkt man lieber einen eisgek\u00fchlten Frapp\u00e9, Kaffee mit Eis und viel Zucker. Er l\u00e4sst sich leicht mitnehmen, und wenn man ein wenig getrunken hat, kann man ihn sp\u00e4ter wieder auff\u00fcllen. Ideal, vor allem f\u00fcr Radfahrer. Bei dem warmen Wetter in der Region <a href=\"https:\/\/cyclingdestination.cc\/de\/verhalen\/fietsen-in-griekenland-op-avontuur-in-west-macedonie\/\">Westmazedonien<\/a> ein eisgek\u00fchlter Frapp\u00e9 schmeckt auch ein bisschen besser als ein lauwarmer Espresso. Wenn Sie in Nordgriechenland mit dem Fahrrad unterwegs sind, hier ein Tipp: Ohne Zucker ist er ein Flop. Ich bleibe vorerst bei hei\u00dfem Kaffee aus der Nespresso-Maschine am Morgen. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"7769\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/07\/20220625_175704-1024x768.jpg\" alt=\"\" class=\"wp-image-7769\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/07\/20220625_175704-1024x768.jpg 1024w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/07\/20220625_175704-300x225.jpg 300w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/07\/20220625_175704-768x576.jpg 768w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/07\/20220625_175704-1536x1152.jpg 1536w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/07\/20220625_175704-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Mechaniker Philippos <\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c4u\u00dferlich ist die <a href=\"https:\/\/gr.top10place.com\/fixit-897612103.html\" target=\"_blank\" rel=\"noreferrer noopener\">Werkstatt<\/a> von Philippos \u00fcber einen Second-Hand-Handy-Reparaturshop, von denen es auch in den Niederlanden viele gibt. Das Sprichwort \"Beurteile ein Buch nie nach seinem Umschlag\" trifft hier sicherlich zu. Zuerst werde ich in den griechischen Einfallsreichtum eingef\u00fchrt. Eine antike Erfindung, um eine Schiebet\u00fcr 'automatisch' zu machen. Mit einer Flasche Wasser und einem St\u00fcck Schnur. Genial in seiner Einfachheit, und es bringt Fahrer Lambros zu einem weiteren seiner ansteckenden Lacher. In der Zwischenzeit sieht sich Philippos mein Fahrrad mit dem Auge eines Schreiners an. Das Problem war eine verbogene Bremsscheibe, aber in der Zwischenzeit fiel sein Blick auch auf meinen Umwerfer. Der war nicht ganz in Ordnung. Ich hatte das nicht gesehen, aber er schon. Er stellte einfach die Shimano Di2 meines Optimum in den Einstellmodus und f\u00fcnf Minuten sp\u00e4ter war das Problem gel\u00f6st. Ich nenne ihn zu Recht einen Fahrradfl\u00fcsterer. <\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1536\" height=\"2048\" data-id=\"7597\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/EA5FA082-B844-4C59-9199-6409DB96A752_1_102_o.jpeg\" alt=\"philippos, kastoria, Mechaniker, Radfahren in Griechenland, Griechenland, Mazedonien\" class=\"wp-image-7597\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/EA5FA082-B844-4C59-9199-6409DB96A752_1_102_o.jpeg 1536w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/EA5FA082-B844-4C59-9199-6409DB96A752_1_102_o-225x300.jpeg 225w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/EA5FA082-B844-4C59-9199-6409DB96A752_1_102_o-768x1024.jpeg 768w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"2560\" height=\"1920\" data-id=\"7612\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6174-1-scaled.jpeg\" alt=\"\" class=\"wp-image-7612\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6174-1-scaled.jpeg 2560w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6174-1-300x225.jpeg 300w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6174-1-1024x768.jpeg 1024w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6174-1-768x576.jpeg 768w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6174-1-1536x1152.jpeg 1536w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6174-1-2048x1536.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Florina nach Nimpheio<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Mit einem festen Fahrrad geht es in die Berge. Heute ist das Ziel, die Strecke zwischen Florina, dem Vegoritida-See und schlie\u00dflich den Anstieg nach Nimpheio zu erkunden. Um dorthin zu gelangen, werfen wir das Fahrrad in den Kofferraum und fahren zum Ausgangspunkt Florina. Auf dem Weg dorthin fahren wir \u00fcber einen herrlichen Anstieg zur Skistation von Vitsi. Ja, in der Tat. Auch hier gibt es eine weitere Skistation. Diesmal ist es eine einzelne Wiese mit einem einfachen Lift, aber auch hier kann man im Winter seine Skier ausprobieren. Der Aufstieg ist relativ steil, aber gut asphaltiert. Man kommt auf einer sch\u00f6nen Anh\u00f6he an und f\u00e4hrt dort in einen griechischen Armeest\u00fctzpunkt. Trotz der tollen Aussicht sollte man nicht vergessen, dass Fotos von diesem Ort nicht erw\u00fcnscht sind. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">&nbsp;Florina<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Das kleine St\u00e4dtchen Florina liegt auf dem Bergr\u00fccken des Varnoundas nahe der Grenze zu Nordmazedonien. Auf einem Kreisverkehr in der N\u00e4he des Stadtplatzes f\u00e4llt ein Tanzb\u00e4r mit einem Cello ins Auge. Der Zusammenhang ist mir noch nicht ganz klar. Die Stadt hat eine reiche und st\u00fcrmische Geschichte.<strong> <\/strong>Als wir uns f\u00fcr eine Fahrradtour fertig machen, lassen wir uns in der Lobby des schicken F\u00fcnf-Sterne-Hotels nieder <a href=\"https:\/\/thelynxcasino.gr\/en\/accommodation\/\" target=\"_blank\" rel=\"noreferrer noopener\">Der Luchs<\/a>. Von hier aus hat man einen wahnsinnigen Blick auf die Stadt, und was die Ausstattung angeht, ist es ideal f\u00fcr ein Basislager. Der Kaffee schmeckt gut und der Service ist erstklassig. Ich steige hier auf mein Fahrrad und fahre in Richtung Evora am Vegoritida-See. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Raus aus der Stadt, rein in die Natur.&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Von Florina aus f\u00fchrt eine Provinzstra\u00dfe in gerader Linie nach Amintaio. Obwohl der Stra\u00dfenbelag vielleicht besser ist, beschlie\u00dfe ich, nach einigen Kilometern au\u00dferhalb der Stadt eine kleine Umkehr zu planen. Ich fahre die gr\u00f6\u00dfere Stra\u00dfe hinunter und finde mich sofort in einer Zeitmaschine wieder. Ein verlassener Busbahnhof, der zum Teil ausgewachsen ist, aber auch noch einen funktionierenden Bus aufzuhalten scheint. Das Besondere. Verfallene Geb\u00e4ude sind mit Ackerfeldern durchsetzt. Ich fahre durch kleine D\u00f6rfer, in denen die Sonne den Tagesrhythmus vorgibt und die \u00e4lteren (m\u00e4nnlichen) Einwohner sich bei Kaffee und guten Gespr\u00e4chen vergn\u00fcgen. Die ungl\u00e4ubigen Blicke, wenn sie einen Rennradfahrer sehen, muss man einfach festhalten. Auffallend ist, dass die Stra\u00dfen au\u00dferhalb des Dorfes oft mehr als gut sind, aber im Dorf muss man immer noch dem einen oder anderen Schlagloch ausweichen. Der Charme des Radfahrens in Nordgriechenland.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"2560\" data-id=\"7616\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6239-scaled.jpeg\" alt=\"\" class=\"wp-image-7616\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6239-scaled.jpeg 1440w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6239-169x300.jpeg 169w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6239-576x1024.jpeg 576w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6239-768x1365.jpeg 768w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6239-864x1536.jpeg 864w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6239-1152x2048.jpeg 1152w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"2560\" data-id=\"7615\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6243-scaled.jpeg\" alt=\"Radreiseziel, Radfahren, Radfahren in Griechenland\" class=\"wp-image-7615\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6243-scaled.jpeg 1440w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6243-169x300.jpeg 169w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6243-576x1024.jpeg 576w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6243-768x1365.jpeg 768w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6243-864x1536.jpeg 864w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6243-1152x2048.jpeg 1152w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Unerwartet ungepflastert<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die fast verlassene Bahnlinie f\u00fchrt mich auf meinem Weg. Ich erwarte jeden Moment den G\u00fcterzug, aber der kommt heute offenbar nicht. Ich biege rechts ab und die Stra\u00dfe entlang der Bahnlinie ist eine Mischung aus gutem Asphalt und festem Schotter. Mit einem Rennrad kein Problem, aber Vorsicht vor gro\u00dfen Steinen. Das stand nicht ganz in der Streckenbeschreibung. In der Zwischenzeit begegnen mir mehrere Traktoren und jedes Mal ein verwunderter Blick: \"Was macht der gro\u00dfe Holl\u00e4nder hier? Das n\u00e4chste Dorf naht, und an einer T-Kreuzung weist mich der Wahoo nach links. Ein kleiner Fehler, ein 'komootje', wie wir es nennen. Die Stra\u00dfe verwandelt sich schnell in einen groben Schotterstreifen. Ein Traktor kommt mir entgegen, und der Mann macht bereits seltsame Gesten. Was kommt dabei heraus? 200 Meter weiter muss ich durch einen tiefen, mit Wasser gef\u00fcllten Graben fahren. So sieht Radfahren in Nordgriechenland aus!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dank eines Balkens an der Seite komme ich trockenen Fu\u00dfes hin\u00fcber. Ich werfe einen Blick auf die Karte und sehe, dass die Hauptstra\u00dfe und damit der gute Asphalt in wenigen hundert Metern auf mich wartet. Manchmal hei\u00dft es auch, zu akzeptieren und mit dem zu arbeiten, was man hat. Fr\u00fcher h\u00e4tte ich mich \u00fcber so etwas ziemlich ge\u00e4rgert. Hier im sch\u00f6nen Griechenland lasse ich es an mir vorbeiziehen. Vielleicht sp\u00e4ter ein extra Frapp\u00e9?&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" data-id=\"7636\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6256-576x1024.jpeg\" alt=\"\" class=\"wp-image-7636\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6256-576x1024.jpeg 576w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6256-169x300.jpeg 169w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6256-768x1366.jpeg 768w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6256-864x1536.jpeg 864w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6256-1151x2048.jpeg 1151w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6256-scaled.jpeg 1439w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" data-id=\"7637\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6255-576x1024.jpeg\" alt=\"\" class=\"wp-image-7637\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6255-576x1024.jpeg 576w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6255-169x300.jpeg 169w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6255-768x1365.jpeg 768w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6255-864x1536.jpeg 864w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6255-1152x2048.jpeg 1152w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6255-scaled.jpeg 1440w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Offene Landschaft<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die gr\u00f6\u00dfere Stra\u00dfe f\u00fchrt \u00fcber eine kurze Steigung entlang der Bahnlinie nach Amintaio. Oben am Anstieg \u00f6ffnet sich die Landschaft und man sieht einerseits den See, andererseits aber auch die Kraftwerke der Region. Ein besonderer Anblick und zugleich eine Erinnerung daran, dass die Energiewende noch in vollem Gange ist oder manchmal erst noch beginnt. Die Anwesenheit der Sonne k\u00f6nnte eine sch\u00f6ne Alternative sein. Ebenso wie eine Umstellung auf das Radfahren in der Stadt. Denn das bleibt ein heikles Thema. In allen St\u00e4dten ist das Auto das Verkehrsmittel. Das ist wirklich schade, denn die Altstadt von Kastoria w\u00e4re sicherlich eine sch\u00f6ne Fu\u00dfg\u00e4ngerzone, in der die Menschen leben und sich wohlf\u00fchlen k\u00f6nnen. Die Zeit wird es zeigen, das wei\u00df ich auch von meinen Reisebegleitern.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1439\" data-id=\"7603\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6287-scaled.jpeg\" alt=\"radfahren in griechenland, griechenland, radfahren, fahrrad, radfahren griechenland, nordgriechenland, nordgriechenland\" class=\"wp-image-7603\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6287-scaled.jpeg 2560w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6287-300x169.jpeg 300w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6287-1024x576.jpeg 1024w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6287-768x432.jpeg 768w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6287-1536x864.jpeg 1536w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6287-2048x1151.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Freund Spyros<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Kurz bevor ich in die Stadt fahre, f\u00e4hrt mein Freund Spyros mit dem Auto neben mir her. Zuerst denke ich, dass ein Verr\u00fcckter versucht, mich von der Stra\u00dfe zu dr\u00e4ngen, aber es stellt sich heraus, dass es jemand ist, den ich kenne. Beurteile ein Buch nie nach seinem Umschlag. Ein paar Kilometer sp\u00e4ter treffen wir uns und die herzliche Begr\u00fc\u00dfung verr\u00e4t genug. Ich habe einen griechischen Freund gewonnen. Gemeinsam starten wir den zweiten Teil in Richtung Evora. Ein Aussichtspunkt \u00fcber dem Vegoritida-See, wo eine Energie-Kommune ein sch\u00f6nes Restaurant betreibt und Aktivit\u00e4ten anbietet.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Stra\u00dfe dorthin ist gut asphaltiert. Wir fahren durch die Weinberge eines der gr\u00f6\u00dften Produzenten der Region. Es ist sehr empfehlenswert, f\u00fcr einen Besuch und eine Verkostung hierher zur\u00fcckzukehren. Er bildet einen sch\u00f6nen Vordergrund f\u00fcr den dahinter liegenden Bergr\u00fccken. Den Anstieg nach Kella kann man sch\u00f6n gegen den Bergr\u00fccken sehen. Hat jemand Haarnadelkurven gesagt?<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-6 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"7619\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6300-1024x576.jpeg\" alt=\"cyclonews.gr, spyros, radfahren, radfahren, radfahren in griechenland, see, anstieg, anstieg nach evora, radfahren in westmakedonien\" class=\"wp-image-7619\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6300-1024x576.jpeg 1024w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6300-300x169.jpeg 300w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6300-768x432.jpeg 768w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6300-1536x864.jpeg 1536w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6300-2048x1152.jpeg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"7620\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6292-1024x576.jpeg\" alt=\"cyclonews.gr, spyros, radfahren, radfahren, radfahren in griechenland, see, klettern, evora, radfahren in westmazedonien\" class=\"wp-image-7620\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6292-1024x576.jpeg 1024w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6292-300x169.jpeg 300w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6292-768x432.jpeg 768w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6292-1536x864.jpeg 1536w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6292-2048x1152.jpeg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Der See und der Aufstieg<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Der Vegoritida-See ist ein riesiges Wasserbecken, das teilweise von den Bergen an der Grenze zu Nordmazedonien umgeben ist. Auf der S\u00fcdseite des Sees wird Ackerbau betrieben und es besteht eine Verbindung zum Rest der Region. Die Stra\u00dfe, die entlang des Sees verl\u00e4uft, ist teilweise gesch\u00fctzt. W\u00e4hrend meiner Reise ist die Temperatur ziemlich hoch und der Gegenwind, den wir haben, wirkt eher wie ein F\u00f6hn als wie eine Klimaanlage. Das ist sehr schade. Zusammen mit Spyros legen wir ein gutes Tempo vor. Am oberen Ende des Sees angekommen, schl\u00e4ngelt sich die Stra\u00dfe durch landwirtschaftliche Felder. Hier gibt es Obst- und Weing\u00e4rten. Die (meist) albanischen Arbeiter schuften sich in der Hitze den Arsch ab. Der F\u00f6hnwind und die brennende Sonne bringen mich dazu, selbst ein wenig zu kochen. Wir n\u00e4hern uns dem Fu\u00df des Anstiegs nach Evora und im Dorf Panagitsa stellen wir das Rad auf dem Platz ab, um ein kaltes Wasser zu trinken. K\u00f6stlich.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-7 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" data-id=\"7622\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6317-scaled.jpeg\" alt=\"radfahren, radfahren in griechenland, radfahren, fahrrad\" class=\"wp-image-7622\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6317-scaled.jpeg 2560w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6317-300x169.jpeg 300w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6317-1024x576.jpeg 1024w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6317-768x432.jpeg 768w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6317-1536x864.jpeg 1536w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6317-2048x1152.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Evora<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Der Aufstieg nach Evora ist ein Erlebnis. Vom Dorf aus f\u00e4hrt man eine zentrale Stra\u00dfe hinunter, in die der \u00f6rtliche Architekt eine Art Pendel gebaut hat. Als wir losfahren, schreien uns mehrere Bewohner alles M\u00f6gliche auf Griechisch zu. Spyros h\u00f6rt es nicht und ich verstehe es nicht. Ich l\u00e4chle die zahnlose Gro\u00dfmutter freundlich an, die mir 'Giro' nachruft. Dieses L\u00e4cheln verschwindet wie Schnee in der Sonne, denn sobald man das Dorf verl\u00e4sst, wartet ein b\u00f6sartiger Killer auf einen. Im \u00fcbertragenen Sinne, denn es handelt sich um einen Anstieg, bei dem auf 2,5 Kilometern 280 H\u00f6henmeter \u00fcberwunden werden. Sie haben richtig gelesen. Das ist die bessere Stampfarbeit. Freund Spyros beginnt schon bald, im Zickzack die Stra\u00dfe entlang zu laufen. Mein H\u00f6hentraining in der Schweiz scheint sich hier auszuzahlen, denn ich kann gut weiterfahren.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-8 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"2560\" data-id=\"7623\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6329-scaled.jpeg\" alt=\"Spyros, Radfahren, Radfahren in Griechenland, Evero, Aufstieg, Aufstieg nach Evora, Radfahren in Westmakedonien, Radfahren in Nordgriechenland\" class=\"wp-image-7623\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6329-scaled.jpeg 1440w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6329-169x300.jpeg 169w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6329-576x1024.jpeg 576w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6329-768x1365.jpeg 768w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6329-864x1536.jpeg 864w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6329-1152x2048.jpeg 1152w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"2560\" data-id=\"7621\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6331-scaled.jpeg\" alt=\"cyclonews.gr, spyros, radfahren, radfahren, radfahren in griechenland, evero, anstieg, anstieg nach evora, radfahren in westmakedonien, radfahren in nordgriechenland\" class=\"wp-image-7621\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6331-scaled.jpeg 1440w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6331-169x300.jpeg 169w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6331-576x1024.jpeg 576w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6331-768x1366.jpeg 768w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6331-864x1536.jpeg 864w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6331-1152x2048.jpeg 1152w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Ansichten und mehr Ansichten<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">'Wo ist dieser Evora jetzt! ', ruft mein griechischer Kumpel mir hinterher. Im Dorf hatte ihm jemand zugefl\u00fcstert, dass es nur noch eineinhalb Kilometer seien. Dieser letzte Kilometer ist genau das Problem. Unter zehn Prozent geht es nicht mehr, und mit Spitzenwerten von siebzehn Prozent geht es hier rauf und runter. Wir halten etwa 400 Meter unterhalb des Gipfels an. Und warum? Die Aussicht hier ist der Wahnsinn und die einzige Haarnadelkurve des Aufstiegs bietet tolle Fotom\u00f6glichkeiten. Dass wir dabei auch verschnaufen k\u00f6nnen, ist ein zus\u00e4tzlicher Bonus. Wir rollen die letzten Meter hinauf, und dort wartet unser Support-Team auf uns. Sie haben sich bereits an den Pfannkuchen des Restaurants satt gegessen und Lambros trinkt noch einen Eiskaffee. Wir setzen uns in den Schatten. Eines ist sicher. F\u00fcr heute ist es geschafft.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-9 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" data-id=\"7630\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6346-scaled.jpeg\" alt=\"switchbacks, radfahren, radfahren in griechenland, radfahren in griechenland, griechenland, radfahren, klettern, evora, spyros, cyclonews.gr\" class=\"wp-image-7630\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6346-scaled.jpeg 2560w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6346-300x169.jpeg 300w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6346-1024x576.jpeg 1024w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6346-768x432.jpeg 768w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6346-1536x864.jpeg 1536w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6346-2048x1152.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1440\" data-id=\"7629\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6353-scaled.jpeg\" alt=\"switchbacks, radfahren, radfahren in griechenland, radfahren in griechenland, griechenland, radfahren, klettern, evora, radfahren in nordgriechenland\" class=\"wp-image-7629\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6353-scaled.jpeg 2560w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6353-300x169.jpeg 300w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6353-1024x576.jpeg 1024w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6353-768x432.jpeg 768w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6353-1536x864.jpeg 1536w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6353-2048x1152.jpeg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Die Stra\u00dfe nach Nympheo<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nach einer l\u00e4ngeren Pause fahren wir hinunter, um ein paar Fotos zu machen, aber dann werfen wir die Fahrr\u00e4der auf den R\u00fccksitz und fahren in Richtung Nympheo, unserem eigentlichen Ziel. Es sind so lange Tage, und da wir auch aus einem anderen Grund hier sind, ist es kein Luxus, einen Teil davon mit dem Auto zu fahren. Schlie\u00dflich m\u00fcssen wir noch H\u00e4nde sch\u00fctteln, Kaffee trinken und Lambros hat unter dem Vorwand, sich die Beine zu vertreten, einen Nikotinhunger, der gestillt werden muss.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Weg nach Nympheo f\u00fchrt meist durch D\u00f6rfer und \u00fcber gr\u00f6\u00dfere Stra\u00dfen. Es ist ziemlich ruhig hier in Bezug auf den Verkehr. Sie arbeiten auch in Richtung der W\u00fcste und das ist der Aufstieg und Ziel an der Spitze dieser sch\u00f6nen Aufstieg.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Nympho<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Stadt Nimfeo wurde fr\u00fcher Neveska genannt. Dieses Wort hatte drei Bedeutungen: Hell, verschneit, verborgen. Hell, verschneit und versteckt. Das Dorf liegt versteckt auf einem Berg, es schneit und es ist ein sch\u00f6ner Ort. Daher. Radfahren in Griechenland ist immer wieder \u00fcberraschend. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Anstieg ist eine Strecke, f\u00fcr die man trainieren sollte. Steil, fast sieben Kilometer lang und mit einer maximalen Steigung von 16 Prozent, ist dies ein fast Vuelta-w\u00fcrdiger Anstieg, und das in Nordgriechenland! Aber Achtung: Es handelt sich nicht um einen Ziegenpfad, sondern um eine gut asphaltierte Stra\u00dfe, und ich kann nur sagen: \"Wow\", als ich hinauffahre. Die Steigung bringt einen so hoch \u00fcber das Tal und das Hinterland, das wir gerade mit dem Auto durchquert haben. Das hat zur Folge, dass die Aussichten von bizarrer Sch\u00f6nheit sind. Man kann kilometerweit sehen, es gibt mehrere Seen, Bergk\u00e4mme und wenn man genau z\u00e4hlt, sieht man vier Kraftwerke, die das Bild vervollst\u00e4ndigen. Ich finde sie nicht unpassend in dieser Region.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-10 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" data-id=\"7632\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6370-576x1024.jpeg\" alt=\"\" class=\"wp-image-7632\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6370-576x1024.jpeg 576w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6370-169x300.jpeg 169w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6370-768x1365.jpeg 768w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6370-864x1536.jpeg 864w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6370-1152x2048.jpeg 1152w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6370-scaled.jpeg 1440w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"7633\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6378-768x1024.jpeg\" alt=\"\" class=\"wp-image-7633\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6378-768x1024.jpeg 768w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6378-225x300.jpeg 225w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6378-1152x1536.jpeg 1152w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6378-1536x2048.jpeg 1536w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6378-scaled.jpeg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" data-id=\"7631\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6352-576x1024.jpeg\" alt=\"\" class=\"wp-image-7631\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6352-576x1024.jpeg 576w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6352-169x300.jpeg 169w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6352-768x1365.jpeg 768w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6352-864x1536.jpeg 864w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6352-1152x2048.jpeg 1152w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6352-scaled.jpeg 1440w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Ein Besuch am Don<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Oben angekommen, f\u00e4hrt man auf die sch\u00f6ne Stadt Nympheo zu. Wir biegen links ab zu einem Hotel. Na ja, es ist eher ein Herrenhaus mit einem riesigen Garten. Als wir parken, kann ich nur feststellen, wie surreal die Umgebung ist. Ein riesiger Garten mit einer Terrasse, auf der sich 40 Leute im Nu niederlassen k\u00f6nnten. Es sitzt jedoch nur eine Person dort. Ein Mann mit Panamahut, Spazierstock und Sonnenbrille, der im Schatten auf unsere Ankunft wartet. In dieser Umgebung stelle ich mir vor, dass ich Don Corleone aus Der Pate besuche. Scherzhaft schicke ich meiner Frau eine App: 'Was auch immer passiert, ich liebe dich'. Nat\u00fcrlich ist auch hier die Realit\u00e4t anders, als man denkt. Der Mann, um den es geht, ist der Besitzer des Hauses, das auch als Hotel dient. Er ist sehr gastfreundlich, engagiert und hat eine Vision. Er entschuldigt sich f\u00fcr sein schlechtes Englisch, aber ich sp\u00fcre, dass er froh ist, dass wir hier sind.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-11 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"7635\" src=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/NympheoCD-1024x768.jpeg\" alt=\"\" class=\"wp-image-7635\" srcset=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/NympheoCD-1024x768.jpeg 1024w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/NympheoCD-300x225.jpeg 300w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/NympheoCD-768x576.jpeg 768w, https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/NympheoCD.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Wunderbarer Ort zum Verweilen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">In dem angrenzenden Hotel, das eigentlich eine Art Herrenhaus ist, ist Platz f\u00fcr etwa 30 G\u00e4ste geschaffen worden. Das Haus geh\u00f6rte einem ehemaligen Chauffeur und wurde tats\u00e4chlich so restauriert, wie es eben war. Gut gepflegt, aber auch mit viel Liebe zum Detail. Ein wunderbarer Ort, um zu enden oder um von hier aus die Umgebung zu erkunden. Aber denken Sie daran: Sie m\u00fcssen jedes Mal den Berg hinaufgehen. Es ist also sehr steil. Aber wenn man einmal oben ist, verschwindet alles, wie Schnee in der Sonne!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Route<\/h2>\n\n\n\n<iframe src=\"https:\/\/www.komoot.nl\/tour\/819610339\/embed?share_token=aUyG3AqSzN20XGqH9PiLsMNPh7Ejj4dkbZ7hSkWAFqmiZRj11V&amp;profile=1\" width=\"100%\" height=\"600\" frameborder=\"0\" scrolling=\"no\"><\/iframe>","protected":false},"excerpt":{"rendered":"<p>Koffie is de motor van de Griekse ochtendsamenleving. Niemand gaat op weg zonder koffie. Op de weg naar Kastoria zag ik zelfs een heuse &#8216;Coffee-drive-in&#8217;. Zelfs voor Nederland, waar we koffie drinken bij elk overleg, is dat een stap te ver. Hier drinkt men het liefst een ijskoude frapp\u00e9, koffie met ijs en veel suiker. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7630,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"iawp_total_views":238,"footnotes":""},"categories":[32,8],"tags":[],"class_list":["post-7571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-griekenland","category-verhalen"],"acf":[],"featured_image_url":{"thumbnail":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6346-150x150.jpeg","medium":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6346-300x169.jpeg","medium_large":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6346-768x432.jpeg","large":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6346-1024x576.jpeg","1536x1536":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6346-1536x864.jpeg","2048x2048":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6346-2048x1152.jpeg","trp-custom-language-flag":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6346-scaled.jpeg"},"post_author":"Sander","assigned_categories":"Griekenland, Verhalen","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fietsen in Noord-Griekenland - Cycling Destination<\/title>\n<meta name=\"description\" content=\"Fietsen in Noord-Griekenland en zeker West-Macedoni\u00eb is verrassend en uitdagend. Fietsen langs meren en wijngaarden!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyclingdestination.cc\/de\/verhalen\/fietsen-in-noord-griekenland-van-florina-naar-nimfeio\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fietsen in Noord-Griekenland - Cycling Destination\" \/>\n<meta property=\"og:description\" content=\"Fietsen in Noord-Griekenland en zeker West-Macedoni\u00eb is verrassend en uitdagend. Fietsen langs meren en wijngaarden!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyclingdestination.cc\/de\/verhalen\/fietsen-in-noord-griekenland-van-florina-naar-nimfeio\/\" \/>\n<meta property=\"og:site_name\" content=\"Cycling Destination\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/cyclingdestination.cc\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-28T07:09:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-02T09:27:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6346-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sander\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@cyclingdestin\" \/>\n<meta name=\"twitter:site\" content=\"@cyclingdestin\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sander\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"15\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-noord-griekenland-van-florina-naar-nimfeio#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-noord-griekenland-van-florina-naar-nimfeio\"},\"author\":{\"name\":\"Sander\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#\\\/schema\\\/person\\\/aba0e58245c092d7cab7d9efba87d8c1\"},\"headline\":\"Fietsen in Noord-Griekenland: van Florina naar Nimfeio\",\"datePublished\":\"2022-06-28T07:09:22+00:00\",\"dateModified\":\"2022-07-02T09:27:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-noord-griekenland-van-florina-naar-nimfeio\"},\"wordCount\":2205,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-noord-griekenland-van-florina-naar-nimfeio#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingdestination.cc\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG_6346-scaled.jpeg\",\"articleSection\":[\"Griekenland\",\"Verhalen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-noord-griekenland-van-florina-naar-nimfeio#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-noord-griekenland-van-florina-naar-nimfeio\",\"url\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-noord-griekenland-van-florina-naar-nimfeio\",\"name\":\"Fietsen in Noord-Griekenland - Cycling Destination\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-noord-griekenland-van-florina-naar-nimfeio#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-noord-griekenland-van-florina-naar-nimfeio#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyclingdestination.cc\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG_6346-scaled.jpeg\",\"datePublished\":\"2022-06-28T07:09:22+00:00\",\"dateModified\":\"2022-07-02T09:27:29+00:00\",\"description\":\"Fietsen in Noord-Griekenland en zeker West-Macedoni\u00eb is verrassend en uitdagend. Fietsen langs meren en wijngaarden!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-noord-griekenland-van-florina-naar-nimfeio#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-noord-griekenland-van-florina-naar-nimfeio\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-noord-griekenland-van-florina-naar-nimfeio#primaryimage\",\"url\":\"https:\\\/\\\/cyclingdestination.cc\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG_6346-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/cyclingdestination.cc\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG_6346-scaled.jpeg\",\"width\":2560,\"height\":1440,\"caption\":\"switchbacks, cycling, cycling in greece, fietsen in griekenland, griekenland, greece, fietsen, klim, evora, spyros, cyclonews.gr\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/verhalen\\\/fietsen-in-noord-griekenland-van-florina-naar-nimfeio#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cyclingdestination.cc\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fietsen in Noord-Griekenland: van Florina naar Nimfeio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#website\",\"url\":\"https:\\\/\\\/cyclingdestination.cc\\\/\",\"name\":\"Cycling Destination\",\"description\":\"Inspiratie voor jouw volgende fietsavontuur\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyclingdestination.cc\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#organization\",\"name\":\"Cycling Destination\",\"url\":\"https:\\\/\\\/cyclingdestination.cc\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyclingdestination.cc\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/cyclingdestination_logo_RGB_zwart_vDEF-1.png\",\"contentUrl\":\"https:\\\/\\\/cyclingdestination.cc\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/cyclingdestination_logo_RGB_zwart_vDEF-1.png\",\"width\":2550,\"height\":814,\"caption\":\"Cycling Destination\"},\"image\":{\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/cyclingdestination.cc\",\"https:\\\/\\\/x.com\\\/cyclingdestin\",\"https:\\\/\\\/www.instagram.com\\\/cyclingdestination.cc\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyclingdestination.cc\\\/#\\\/schema\\\/person\\\/aba0e58245c092d7cab7d9efba87d8c1\",\"name\":\"Sander\",\"url\":\"https:\\\/\\\/cyclingdestination.cc\\\/de\\\/author\\\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Radfahren in Nordgriechenland - Radreiseziel","description":"Radfahren in Nordgriechenland und vor allem in Westmazedonien ist \u00fcberraschend und herausfordernd. Radfahren an Seen und Weinbergen vorbei!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyclingdestination.cc\/de\/verhalen\/fietsen-in-noord-griekenland-van-florina-naar-nimfeio\/","og_locale":"de_DE","og_type":"article","og_title":"Fietsen in Noord-Griekenland - Cycling Destination","og_description":"Fietsen in Noord-Griekenland en zeker West-Macedoni\u00eb is verrassend en uitdagend. Fietsen langs meren en wijngaarden!","og_url":"https:\/\/cyclingdestination.cc\/de\/verhalen\/fietsen-in-noord-griekenland-van-florina-naar-nimfeio\/","og_site_name":"Cycling Destination","article_publisher":"https:\/\/www.facebook.com\/cyclingdestination.cc","article_published_time":"2022-06-28T07:09:22+00:00","article_modified_time":"2022-07-02T09:27:29+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6346-scaled.jpeg","type":"image\/jpeg"}],"author":"Sander","twitter_card":"summary_large_image","twitter_creator":"@cyclingdestin","twitter_site":"@cyclingdestin","twitter_misc":{"Verfasst von":"Sander","Gesch\u00e4tzte Lesezeit":"15\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-noord-griekenland-van-florina-naar-nimfeio#article","isPartOf":{"@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-noord-griekenland-van-florina-naar-nimfeio"},"author":{"name":"Sander","@id":"https:\/\/cyclingdestination.cc\/#\/schema\/person\/aba0e58245c092d7cab7d9efba87d8c1"},"headline":"Fietsen in Noord-Griekenland: van Florina naar Nimfeio","datePublished":"2022-06-28T07:09:22+00:00","dateModified":"2022-07-02T09:27:29+00:00","mainEntityOfPage":{"@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-noord-griekenland-van-florina-naar-nimfeio"},"wordCount":2205,"commentCount":0,"publisher":{"@id":"https:\/\/cyclingdestination.cc\/#organization"},"image":{"@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-noord-griekenland-van-florina-naar-nimfeio#primaryimage"},"thumbnailUrl":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6346-scaled.jpeg","articleSection":["Griekenland","Verhalen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-noord-griekenland-van-florina-naar-nimfeio#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-noord-griekenland-van-florina-naar-nimfeio","url":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-noord-griekenland-van-florina-naar-nimfeio","name":"Radfahren in Nordgriechenland - Radreiseziel","isPartOf":{"@id":"https:\/\/cyclingdestination.cc\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-noord-griekenland-van-florina-naar-nimfeio#primaryimage"},"image":{"@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-noord-griekenland-van-florina-naar-nimfeio#primaryimage"},"thumbnailUrl":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6346-scaled.jpeg","datePublished":"2022-06-28T07:09:22+00:00","dateModified":"2022-07-02T09:27:29+00:00","description":"Radfahren in Nordgriechenland und vor allem in Westmazedonien ist \u00fcberraschend und herausfordernd. Radfahren an Seen und Weinbergen vorbei!","breadcrumb":{"@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-noord-griekenland-van-florina-naar-nimfeio#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-noord-griekenland-van-florina-naar-nimfeio"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-noord-griekenland-van-florina-naar-nimfeio#primaryimage","url":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6346-scaled.jpeg","contentUrl":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/06\/IMG_6346-scaled.jpeg","width":2560,"height":1440,"caption":"switchbacks, cycling, cycling in greece, fietsen in griekenland, griekenland, greece, fietsen, klim, evora, spyros, cyclonews.gr"},{"@type":"BreadcrumbList","@id":"https:\/\/cyclingdestination.cc\/verhalen\/fietsen-in-noord-griekenland-van-florina-naar-nimfeio#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cyclingdestination.cc\/"},{"@type":"ListItem","position":2,"name":"Fietsen in Noord-Griekenland: van Florina naar Nimfeio"}]},{"@type":"WebSite","@id":"https:\/\/cyclingdestination.cc\/#website","url":"https:\/\/cyclingdestination.cc\/","name":"Ziel Radfahren","description":"Inspiration f\u00fcr Ihr n\u00e4chstes Fahrradabenteuer","publisher":{"@id":"https:\/\/cyclingdestination.cc\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyclingdestination.cc\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/cyclingdestination.cc\/#organization","name":"Ziel Radfahren","url":"https:\/\/cyclingdestination.cc\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cyclingdestination.cc\/#\/schema\/logo\/image\/","url":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/01\/cyclingdestination_logo_RGB_zwart_vDEF-1.png","contentUrl":"https:\/\/cyclingdestination.cc\/wp-content\/uploads\/2022\/01\/cyclingdestination_logo_RGB_zwart_vDEF-1.png","width":2550,"height":814,"caption":"Cycling Destination"},"image":{"@id":"https:\/\/cyclingdestination.cc\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/cyclingdestination.cc","https:\/\/x.com\/cyclingdestin","https:\/\/www.instagram.com\/cyclingdestination.cc\/"]},{"@type":"Person","@id":"https:\/\/cyclingdestination.cc\/#\/schema\/person\/aba0e58245c092d7cab7d9efba87d8c1","name":"Sander","url":"https:\/\/cyclingdestination.cc\/de\/author\/admin"}]}},"_links":{"self":[{"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/posts\/7571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/comments?post=7571"}],"version-history":[{"count":0,"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/posts\/7571\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/media\/7630"}],"wp:attachment":[{"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/media?parent=7571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/categories?post=7571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyclingdestination.cc\/de\/wp-json\/wp\/v2\/tags?post=7571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}